{"id":10165,"date":"2025-12-06T13:45:11","date_gmt":"2025-12-06T13:45:11","guid":{"rendered":"https:\/\/test.sweethome3d.eu\/guida-alla-traduzione\/"},"modified":"2025-12-15T18:35:55","modified_gmt":"2025-12-15T18:35:55","slug":"guida-alla-traduzione","status":"publish","type":"page","link":"https:\/\/test.sweethome3d.eu\/it\/guida-alla-traduzione\/","title":{"rendered":"Guida alla traduzione"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Introduzione<\/h2>\n\n<p>Parli una lingua straniera non ancora supportata in <a href=\"\/\">Sweet Home 3D<\/a> e vorresti contribuire alla sua traduzione in quella lingua? Dalla versione 2.3, Sweet Home 3D supporta i file SH3L e questa guida ti insegner\u00e0 come creare un file di questo tipo da solo. Un file SH3L \u00e8 un file di lingua auto-installabile e gli utenti devono solo fare doppio clic su un file SH3L per tradurre Sweet Home 3D nella lingua descritta da quel file.  <\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\">Istruzioni di base<\/h2>\n\n<p>La creazione di un file SH3L consiste in:<\/p>\n\n<ol class=\"wp-block-list default-ol pl-14\">\n<li>scaricare una <a href=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/10\/SweetHome3DTranslation.zip\" data-type=\"attachment\" data-id=\"5143\">versione inglese dei file<\/a> da tradurre,<\/li>\n\n\n\n<li>decomprimere il file scaricato,<\/li>\n\n\n\n<li>aggiungere un <a href=\"https:\/\/www.loc.gov\/standards\/iso639-2\/php\/English_list.php\" target=\"_blank\" rel=\"noopener\">suffisso di 2 lettere corrispondente alla tua lingua<\/a> ai file <code>.properties<\/code> che contiene,<\/li>\n\n\n\n<li>tradurre il testo nei file <code>.properties<\/code>,<\/li>\n\n\n\n<li>convertirli in codifica ASCII,<\/li>\n\n\n\n<li>tradurre il testo della guida nei file <code>.html<\/code> (non obbligatorio, ma sar\u00e0 davvero utile per gli utenti),<\/li>\n\n\n\n<li>zippare nuovamente i file <code>.properties<\/code> e i file della guida in un file con estensione SH3L,<\/li>\n\n\n\n<li>fare doppio clic sul file SH3L per testare la traduzione in Sweet Home 3D,<\/li>\n\n\n\n<li>distribuire il file SH3L.<\/li>\n<\/ol>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\" id=\"detailedInstructions\">Istruzioni dettagliate<\/h2>\n\n<p>Se non hai paura delle istruzioni di base precedenti, vai avanti con i passaggi successivi.<\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h3 class=\"wp-block-heading\">Ottenere la versione inglese<\/h3>\n\n<p>Scarica l&#8217;archivio all&#8217;indirizzo <a href=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/10\/SweetHome3DTranslation.zip\" data-type=\"attachment\" data-id=\"5143\">\/SweetHome3DTranslation.zip<\/a> (versione 7.5) e decomprimilo con gli strumenti del tuo sistema.<br\/><em>SweetHome3DTranslation.zip<\/em> contiene una serie di file con estensioni <code>.properties<\/code> e <code>.html<\/code> posizionati in sottocartelle come mostrato nella figura 1.<\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"972\" height=\"1024\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-26-972x1024.png\" alt=\"\" class=\"wp-image-4437 lazyload\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-26-972x1024.png 972w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-26-285x300.png 285w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-26-85x90.png 85w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-26-768x809.png 768w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-26-1458x1536.png 1458w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-26.png 1562w\" data-sizes=\"(max-width: 972px) 100vw, 972px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 972px; --smush-placeholder-aspect-ratio: 972\/1024;\" \/><figcaption class=\"wp-element-caption\">Figura 1. File di traduzione <\/figcaption><\/figure>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>Tutti i file <code>.properties<\/code> e <code>.html<\/code> contengono la versione inglese dei testi che dovrai tradurre nella tua lingua:<\/p>\n\n<ul class=\"wp-block-list pl-14\">\n<li>i file <code>package.properties<\/code> descrivono etichette, menu e voci di menu visualizzati nell&#8217;interfaccia utente di Sweet Home 3D,<\/li>\n\n\n\n<li>i file <code>basic.properties<\/code> e <code>metal.properties<\/code> descrivono le etichette standard delle finestre di dialogo,<\/li>\n\n\n\n<li>quelli che terminano con <code>Catalog.properties<\/code> descrivono i nomi dei mobili e delle texture disponibili nel software,<\/li>\n\n\n\n<li>i file <code>.html<\/code> contengono il testo della guida di Sweet Home 3D.<\/li>\n<\/ul>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group warning-banner is-nowrap is-layout-flex wp-container-core-group-is-layout-9123dee2 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"190\" height=\"190\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/11\/Frame-281.png\" alt=\"\" class=\"wp-image-786 lazyload\" style=\"--smush-placeholder-width: 190px; --smush-placeholder-aspect-ratio: 190\/190;width:130px\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/11\/Frame-281.png 190w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/11\/Frame-281-90x90.png 90w\" data-sizes=\"(max-width: 190px) 100vw, 190px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer !h-auto wp-container-content-16d1eb73\"><\/div>\n\n\n\n<p>I file .properties devono essere posizionati nelle cartelle mostrate nella figura 1, altrimenti Sweet Home 3D non sar\u00e0 in grado di utilizzarli correttamente. Quindi non spostare i file fuori dalla loro cartella, non rinominare nessuna cartella (eccetto la sottodirectory en di help) e non eliminare nessuna cartella.<\/p>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h3 class=\"wp-block-heading\">Rinominare i file a seconda della lingua<\/h3>\n\n<p>Prima di tradurre i file <code>.properties<\/code>, dovresti rinominare ciascuno di essi aggiungendo al loro nome un trattino basso seguito dal codice ISO a 2 caratteri corrispondente alla tua lingua. Troverai questo codice nell&#8217;ultima colonna del documento <a href=\"https:\/\/www.loc.gov\/standards\/iso639-2\/php\/English_list.php\" target=\"_blank\" rel=\"noopener\">https:\/\/www.loc.gov\/standards\/iso639-2\/php\/English_list.php<\/a>.<br\/>Quindi, se vuoi tradurre i file della guida, dovresti rinominare anche la sottodirectory <code>en<\/code> di <code>help<\/code> con quel codice a 2 lettere.<br\/>Ad esempio, il codice ISO per il ceco \u00e8 <code>cs<\/code>. Se vuoi tradurre Sweet Home 3D in ceco, ogni nome di file dovrebbe avere il suffisso <code>_cs<\/code> e dovresti rinominare i file come mostrato nella figura 2.  <\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"972\" height=\"1024\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-27-972x1024.png\" alt=\"\" class=\"wp-image-4446 lazyload\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-27-972x1024.png 972w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-27-285x300.png 285w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-27-85x90.png 85w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-27-768x809.png 768w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-27-1458x1536.png 1458w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-27.png 1562w\" data-sizes=\"(max-width: 972px) 100vw, 972px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 972px; --smush-placeholder-aspect-ratio: 972\/1024;\" \/><figcaption class=\"wp-element-caption\">Figura 2. File Properties con il loro suffisso di codice ISO <\/figcaption><\/figure>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h3 class=\"wp-block-heading\">Traduzione dei file properties<\/h3>\n\n<p>I file <code>.properties<\/code> sono file di testo semplice e puoi modificarli con qualsiasi editor di testo come <em>Wordpad<\/em>, <em>TextEdit<\/em> o <em>emacs<\/em>. Ad esempio, il file <code>com\/eteks\/sweethome3d\/package.properties<\/code> in Sweet Home 3D 3.0 contiene il seguente testo: <\/p>\n\n<pre class=\"wp-block-preformatted\"><font class=\"codeComment\"># package.properties 10 ott. 2007\n# \n# Copyright (c) 2024 Space Mushrooms &lt;info@sweethome3d.com&gt;. Tutti i diritti riservati.\n# \n# Questo programma \u00e8 software libero; puoi ridistribuirlo e\/o modificarlo secondo\n# i termini della GNU General Public License pubblicata dalla Free Software\n# Foundation; sia la versione 2 della licenza, sia (a tua scelta) qualsiasi versione successiva\n# versione.\n# \n# Questo programma \u00e8 distribuito nella speranza che sia utile, ma SENZA\n# ALCUNA GARANZIA; senza nemmeno la garanzia implicita di COMMERCIABILIT\u00c0 o IDONEIT\u00c0\n# PER UN PARTICOLARE SCOPO.  Vedi la GNU General Public License per maggiori\n# dettagli.\n# \n# Avresti dovuto ricevere una copia della GNU General Public License insieme a\n# questo programma; in caso contrario, scrivi a Free Software Foundation, Inc., 59 Temple\n# Place, Suite 330, Boston, MA 02111-1307 USA\n\n# Risorse per la classe HomeFramePane<\/font>\n<font class=\"propertyKey\">HomeFramePane.untitled<\/font>=Senza titolo\n\n\n<font class=\"codeComment\"># Risorse per la classe MacOSXConfiguration<\/font>\n<font class=\"propertyKey\">MacOSXConfiguration.WINDOW_MENU.Name<\/font>=Finestra\n<font class=\"propertyKey\">MacOSXConfiguration.MINIMIZE.Name<\/font>=Riduci a icona\n<font class=\"propertyKey\">MacOSXConfiguration.ZOOM.Name<\/font>=Zoom\n<font class=\"propertyKey\">MacOSXConfiguration.BRING_ALL_TO_FRONT.Name<\/font>=Porta tutto in primo piano\n\n\n<font class=\"codeComment\"># Risorse per la classe SweetHome3D<\/font>\n<font class=\"propertyKey\">SweetHome3D.3DError.message<\/font>=<font class=\"specialValue\">&lt;html&gt;<\/font> Sweet Home 3D si chiuder\u00e0 ora a causa di un errore irreversibile<font class=\"specialValue\"><\/font>\n    <font class=\"specialValue\">&lt;br&gt;<\/font>nel sistema di rendering 3D. Aggiorna i driver DirectX\/OpenGL<font class=\"specialValue\">\n    <font class=\"specialValue\">&lt;br&gt;<\/font>della tua scheda grafica.<\/font> \n<font class=\"propertyKey\">SweetHome3D.3DError.title<\/font>=Errore 3D\n    \n<font class=\"propertyKey\">SweetHome3D.confirmSaveAfter3DError.message<\/font>=<font class=\"specialValue\">&lt;html&gt;<\/font> Sweet Home 3D deve chiudersi ora a causa di un errore irreversibile in<font class=\"specialValue\"><\/font>\n    <font class=\"specialValue\">&lt;br&gt;<\/font>sistema di rendering 3D. Vuoi salvare tutte le case modificate? \n<font class=\"propertyKey\">SweetHome3D.confirmSaveAfter3DError.title<\/font>=Errore 3D\n<font class=\"propertyKey\">SweetHome3D.confirmSaveAfter3DError.save<\/font>=Salva\n<font class=\"propertyKey\">SweetHome3D.confirmSaveAfter3DError.doNotSave<\/font>=Non salvare<\/pre>\n\n<p>Un file <code>.properties<\/code> contiene tre tipi di righe:<\/p>\n\n<ul class=\"wp-block-list pl-14\">\n<li>le righe che iniziano con un carattere # sono commenti (mostrati in verde nell&#8217;esempio precedente). Alcuni commenti contengono informazioni legali, altri forniscono informazioni a sviluppatori o traduttori. Mantieni queste righe invariate.  <\/li>\n\n\n\n<li>le righe vuote vengono utilizzate solo per separare le varie parti di un file <code>.properties<\/code>.<\/li>\n\n\n\n<li>le altre righe iniziano con del testo utilizzato da Sweet Home 3D come chiave per trovare un testo visualizzato sullo schermo (mostrato in blu nell&#8217;esempio precedente). Dopo questa chiave, ciascuna di queste righe contiene un segno di uguale (<code>=<\/code>) e un testo in una determinata lingua. Il tuo lavoro inizia dai segni di uguale. Non modificare il testo della chiave e sostituisci il testo inglese dopo il segno di uguale con la sua traduzione.   <\/li>\n<\/ul>\n\n<p>Casi speciali:<\/p>\n\n<ul class=\"wp-block-list pl-14\">\n<li>I testi che iniziano con un tag  <font class=\"specialValue\"><code>&lt;html&gt;<\/code><\/font> \n  contengono del testo in formato HTML. Questi testi contengono altri tag \n HTML tra   <font class=\"specialValue\"><code>&lt;<\/code><\/font> \n  e  <font class=\"specialValue\"><code>&gt;<\/code><\/font>  segni, come  \n            <font class=\"specialValue\"><code>&lt;br&gt;<\/code><\/font>  nell&#8217;esempio \n precedente che rappresenta un ritorno a capo nel mezzo di testi lunghi. \n Non rimuovere questi tag HTML, aiutano Sweet Home 3D a presentare correttamente \n alcuni testi. Tradurre il testo tra tag HTML non \u00e8 molto difficile, \n tranne forse per il testo HTML peggiore che \u00e8 il valore della chiave <code>WallPanel.wallOrientationLabel.text<\/code> \n. <\/li>\n\n\n\n<li>Per evitare righe lunghe nell&#8217;editor di testo, alcune righe \n sono divise in due o pi\u00f9 righe e quindi separate da barre rovesciate  \n            <font class=\"specialValue\"><code>\\<\/code><\/font>, come la riga che inizia \n con  <font class=\"propertyKey\"><code>SweetHome3D.3DError.message<\/code><\/font> \n  nell&#8217;esempio precedente. In tal caso, non rimuovere il segno   <font class=\"specialValue\"><code>\\<\/code><\/font> \n  situato alla fine di una riga perch\u00e9 indica che la riga successiva \n segue la riga corrente.<\/li>\n\n\n\n<li>Alcuni testi contengono sequenze di caratteri speciali che iniziano \n con un segno <code> <\/code>% , come <code>%s<\/code>, <code>%d<\/code>, \n            <code>%1$s<\/code>, <code>%2$s<\/code>&#8230; Queste sequenze di caratteri \n verranno sostituite da un nome file, un&#8217;unit\u00e0 o un numero quando necessario, quindi \n non rimuoverle. <br\/> Ad esempio, la sequenza di caratteri   <font class=\"specialValue\"><code>%s<\/code><\/font> \n  nel testo della seguente chiave  <font class=\"propertyKey\"><code>HomeFurniturePanel.widthLabel.text<\/code><\/font>:<br\/>            <pre><font class=\"propertyKey\">HomeFurniturePanel.widthLabel.text<\/font>=Larghezza (<font class=\"specialValue\">%s<\/font>):<\/pre>\n  verr\u00e0 sostituito dall&#8217;unit\u00e0 attualmente in uso. Le due sequenze di caratteri   \n            <font class=\"specialValue\"><code>%1$d<\/code><\/font>  e  <font class=\"specialValue\"><code>%2$d<\/code><\/font> \n  che appaiono nel testo della seguente chiave  <font class=\"propertyKey\"><code>PrintPreviewPanel.pageLabel.text<\/code><\/font>:<br\/>            <pre><font class=\"propertyKey\">PrintPreviewPanel.pageLabel.text<\/font>=Pagina  <font class=\"specialValue\">%1$d<\/font>\/<font class=\"specialValue\">%2$d<\/font><\/pre>\n  appariranno sullo schermo come un numero di pagina e il conteggio delle pagine, e dovresti tradurre solo la parola <code>Page<\/code>.<\/li>\n\n\n\n<li>Alcuni testi contengono anche la sequenza di caratteri speciali  <font class=\"specialValue\"><code>\\n<\/code><\/font>, come nel seguente esempio:  <pre><font class=\"propertyKey\">HomeController.saveError<\/font>=Impossibile salvare la casa in<font class=\"specialValue\">\\n<\/font>\"<font class=\"specialValue\">%s<\/font>\"<\/pre>  Questa sequenza di caratteri viene visualizzata da Sweet Home 3D come un ritorno a capo per dividere una riga sullo schermo e non dovresti rimuoverla.<br\/><\/li>\n\n\n\n<li>Il valore della chiave <code>HelpController.helpIndex<\/code> indica la directory in cui \u00e8 possibile trovare i file della guida. Se traduci i file della guida .<code>html<\/code>, dovresti sostituire la sottodirectory <code>en<\/code> trovata con il codice a 2 lettere della tua lingua. <br\/>Ad esempio, se traduci la guida in ceco, dovrebbe diventare: <br\/><pre><font class=\"propertyKey\">HelpController.helpIndex<\/font>=\/com\/eteks\/sweethome3d\/viewcontroller\/resources\/help\/<font class=\"specialValue\">cs<\/font>\/index.html<\/pre><\/li>\n<\/ul>\n\n<ul class=\"wp-block-list pl-14\">\n<li>Il testo delle chiavi che terminano con <code>.mnemonic<\/code> viene utilizzato da Sweet Home 3D per indovinare quale lettera in un&#8217;etichetta o in una voce di menu deve essere sottolineata per l&#8217;accesso da tastiera. Questa lettera mnemonica dipende dalla parola visualizzata e dovresti trovarne una univoca per ogni finestra di dialogo o menu.<br\/>Ad esempio, i seguenti testi e mnemonici visualizzati nella finestra di dialogo di modifica dei mobili: <br\/><pre><font class=\"propertyKey\">HomeFurniturePanel.nameLabel.text<\/font>=Nome:\n<font class=\"propertyKey\">HomeFurniturePanel.nameLabel.mnemonic<\/font>=<b>N<\/b>\n<font class=\"propertyKey\">HomeFurniturePanel.nameVisibleCheckBox.text<\/font>=Visualizza nome nel piano\n<font class=\"propertyKey\">HomeFurniturePanel.nameVisibleCheckBox.mnemonic<\/font>=<b>S<\/b>\n<font class=\"propertyKey\">HomeFurniturePanel.widthLabel.text<\/font>=Larghezza (%s):\n<font class=\"propertyKey\">HomeFurniturePanel.widthLabel.mnemonic<\/font>=<b>W<\/b><\/pre>\npu\u00f2 essere tradotto in francese da: <br\/><pre><font class=\"propertyKey\">HomeFurniturePanel.nameLabel.text<\/font>=Nom :\n<font class=\"propertyKey\">HomeFurniturePanel.nameLabel.mnemonic<\/font>=<b>N<\/b>\n<font class=\"propertyKey\">HomeFurniturePanel.nameVisibleCheckBox.text<\/font>=Afficher le nom dans le plan\n<font class=\"propertyKey\">HomeFurniturePanel.nameVisibleCheckBox.mnemonic<\/font>=<b>S<\/b>\n<font class=\"propertyKey\">HomeFurniturePanel.widthLabel.text<\/font>=Largeur (%s) :\n<font class=\"propertyKey\">HomeFurniturePanel.widthLabel.mnemonic<\/font>=<b>L<\/b><\/pre>            \n<\/li>\n\n\n\n<li>Usa Sweet Home 3D o la <a href=\"https:\/\/test.sweethome3d.eu\/import-models\/\" data-type=\"page\" data-id=\"432\">pagina di importazione dei modelli 3D<\/a> per aiutarti a tradurre i file <code>.properties<\/code> che terminano con <code>Catalog.properties<\/code>.<\/li>\n<\/ul>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h3 class=\"wp-block-heading\">Conversione dei file properties in codifica ASCII<\/h3>\n\n<p><a><\/a>Se hai tradotto testi in una lingua con lettere non appartenenti alla <a href=\"https:\/\/fr.wikipedia.org\/wiki\/ISO_8859-1\" target=\"_blank\" rel=\"noopener\">codifica ISO-8859-1<\/a> (principalmente lingue dell&#8217;Europa centrale e orientale e lingue con un alfabeto non latino), dovrai convertire tutti i tuoi file <code>.properties<\/code> in una codifica ASCII supportata da Sweet Home 3D. Questa conversione pu\u00f2 essere eseguita con lo strumento <code>native2ascii<\/code> fornito con il <a href=\"https:\/\/java.sun.com\/javase\/downloads\/\" target=\"_blank\" rel=\"noopener\">JDK<\/a> o pu\u00f2 essere eseguita con il seguente modulo.<br\/>Per ogni file <code>.properties<\/code>, crea un backup di quel file, copia\/incolla il testo da convertire nella seguente area di testo, fai clic sul pulsante <em>Converti<\/em> e copia\/incolla il testo convertito nel suo file <code>.properties<\/code>. <\/p>\n\n\n    <form method=\"post\" action=\"\/it\/wp-json\/wp\/v2\/pages\/10165#translationForm\" accept-charset=\"UTF-8\" id=\"translationForm\" style=\"text-align:center;\">\n        <p>\n            <textarea name=\"text\" cols=\"80\" rows=\"6\" wrap=\"off\" id=\"text\"><\/textarea>\n        <\/p>\n        <p>\n            <input type=\"submit\" value=\"Convert\" \/>\n        <\/p>\n    <\/form>\n\n<p>Lo strumento di conversione sostituir\u00e0 ogni carattere non ASCII (lettere latine accentate e lettere non latine) con una sequenza che inizia con <code>\\u<\/code> e seguita da un codice a 4 cifre esadecimali corrispondente a quel carattere in Unicode. Purtroppo, questa conversione render\u00e0 il tuo testo piuttosto illeggibile per un essere umano, ma se non la esegui, Sweet Home 3D non sar\u00e0 in grado di visualizzare correttamente i caratteri della tua traduzione. Questo \u00e8 il motivo per cui dovresti creare un backup dei tuoi file <code>.properties<\/code> originali, nel caso in cui volessi modificarli in seguito.<br\/>Se vuoi modificare direttamente i file <code>.properties<\/code> convertiti in ASCII, puoi anche utilizzare l&#8217;applicazione <a href=\"https:\/\/propedit.sourceforge.jp\/index_en.html\" target=\"_blank\" rel=\"noopener\">Properties Editor<\/a> disponibile come file eseguibile Jar <a href=\"https:\/\/sourceforge.jp\/projects\/propedit\/\" target=\"_blank\" rel=\"noopener\">qui<\/a>.  <\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h3 class=\"wp-block-heading\">Traduzione dei file della guida<\/h3>\n\n<p>Una buona traduzione di Sweet Home 3D dovrebbe includere anche la traduzione dei suoi file della guida. Tradurre tutti i file <code>.html<\/code> \u00e8 un compito lungo, ma aiuter\u00e0 davvero gli utenti a imparare il software ed evitare alcune richieste di supporto nel forum di Sweet Home 3D. Usa qualsiasi editor HTML per tradurre questi file, cercando di mantenere invariati i collegamenti che contiene e il suo foglio di stile.<br\/>Una volta tradotto, dovresti anche creare schermate delle finestre di dialogo nella tua lingua per sostituire le immagini trovate in <code>com\/eteks\/sweethome3d\/viewcontroller\/resources\/help\/en\/images<\/code>. Per essere in grado di creare tali schermate, crea e testa un primo file SH3L con i seguenti passaggi (una volta che esiste un file SH3L contenente file <code>.properties<\/code> tradotti, puoi anche richiedere allo <a href=\"mailto:info@sweethome3d.com\">sviluppatore<\/a> di Sweet Home 3D di generare le schermate).   <\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h3 class=\"wp-block-heading\">Creazione del file SH3L<\/h3>\n\n<p>Una volta che tutti i file <code>.properties<\/code> e <code>.html<\/code> sono tradotti e convertiti in ASCII se necessario (o anche prima se vuoi testare questa procedura), dovresti zipparli in un file. A seconda del tuo sistema, la creazione di un file zip pu\u00f2 essere eseguita con la seguente procedura: <\/p>\n\n<ul class=\"wp-block-list pl-14\">\n<li>in Windows, seleziona la cartella <code>com<\/code> contenente tutti i file tradotti e scegli <em>Invia a &gt; Cartella compressa<\/em> dal suo menu contestuale,<\/li>\n\n\n\n<li>in Mac OS X, seleziona la cartella <code>com<\/code> contenente tutti i file tradotti e scegli la voce di menu <em>File &gt; Comprimi \u00ab com \u00bb<\/em>,<\/li>\n\n\n\n<li>in Linux, seleziona la cartella <code>com<\/code> contenente tutti i file tradotti, scegli <em>Crea archivio\u2026<\/em> dal suo menu contestuale, quindi seleziona <em>.zip<\/em> nell&#8217;elenco dei formati.<\/li>\n<\/ul>\n\n<p>Infine, cambia l&#8217;estensione <code>.zip<\/code> del file zip in <code>.sh3l<\/code>. Un file SH3L pu\u00f2 avere qualsiasi nome, ma per evitare conflitti con i file SH3L esistenti, dovresti nominarlo dalla lingua che contiene e dalla versione di Sweet Home 3D che hai tradotto (ad esempio, <code>French-4.1.sh3l<\/code> potrebbe essere un buon nome per la traduzione francese di Sweet Home 3D 4.1). <\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h3 class=\"wp-block-heading\">Testare un file SH3L<\/h3>\n\n<p>Per testare la traduzione, fai doppio clic su un file SH3L o sceglilo con il pulsante <em>Importa file libreria lingua<\/em> <img decoding=\"async\" width=\"35\" height=\"23\" class=\"wp-image-4454 lazyload\" style=\"--smush-placeholder-width: 35px; --smush-placeholder-aspect-ratio: 35\/23;width: 35px;\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/importLanguageLibraryFile.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/> visualizzato nella parte superiore del pannello <em>Preferenze<\/em>. Questo avvier\u00e0 Sweet Home 3D e tradurr\u00e0 la sua interfaccia utente nella lingua descritta nel file SH3L. Questo copier\u00e0 anche il file SH3L in una cartella a seconda del tuo sistema:  <\/p>\n\n<ul class=\"wp-block-list pl-14\">\n<li>in Windows Vista \/ 7 \/ 8 \/ 10 \/ 11, questa cartella \u00e8 C:\\Users\\<em>utente<\/em>\\AppData\\Roaming\\eTeks\\Sweet Home 3D\\languages,<\/li>\n\n\n\n<li>in Windows XP e versioni precedenti di Windows, questa cartella \u00e8 C:\\Documents and Settings\\<em>utente<\/em>\\Application Data\\eTeks\\Sweet Home 3D\\languages,<\/li>\n\n\n\n<li>in macOS, \u00e8 la sottocartella Library\/Application Support\/eTeks\/Sweet Home 3D\/languages della tua cartella utente,<\/li>\n\n\n\n<li>in Linux e altri Unix, \u00e8 la sottocartella .eteks\/sweethome3d\/languages della tua cartella utente,<\/li>\n\n\n\n<li>con la versione portatile di Sweet Home 3D, \u00e8 la sottocartella data\/languages della cartella in cui \u00e8 memorizzata l&#8217;applicazione Sweet Home 3D,<\/li>\n<\/ul>\n\n<p>Si noti inoltre che durante lo sviluppo del file SH3L, probabilmente sar\u00e0 necessario riavviare Sweet Home 3D per visualizzare le modifiche nel file SH3L.<\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h3 class=\"wp-block-heading\">Distribuzione di file SH3L<\/h3>\n\n<p>Una volta che il file SH3L \u00e8 pronto, \u00e8 possibile proporlo a chiunque, annunciarlo agli utenti di Sweet Home 3D nella <a href=\"\/support\/forum\/listthreads?forum=9\">parte del forum riservata alle lingue straniere<\/a> o in altri luoghi. Se sei d&#8217;accordo, pu\u00f2 essere reso disponibile su questo sito web nella pagina relativa alle <a href=\"https:\/\/test.sweethome3d.eu\/it\/traduzioni\/\" data-type=\"page\" data-id=\"442\">traduzioni<\/a> supportate da Sweet Home 3D. <\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h3 class=\"wp-block-heading\">Aggiornamento dei file SH3L<\/h3>\n\n<p>Alcune versioni di Sweet Home 3D apportano nuove funzionalit\u00e0 da tradurre, altre no. Se non traduci le etichette dell&#8217;interfaccia utente corrispondenti a queste nuove funzionalit\u00e0, Sweet Home 3D funzioner\u00e0, ma tutte le nuove etichette verranno visualizzate in inglese. Per trovare le nuove chiavi e le chiavi aggiornate nei file <code>.properties<\/code>, \u00e8 possibile utilizzare una funzione offerta da SourceForge.net che consente di confrontare due versioni di un file di progetto:  <\/p>\n\n<ol class=\"wp-block-list default-ol pl-14\">\n<li>Cerca le date delle versioni di Sweet Home 3D che vuoi confrontare nella <a href=\"\/history\/\" data-type=\"page\" data-id=\"430\">cronologia<\/a> (ad esempio, 19 luglio 2015 per la versione 5.0 e 2 febbraio 2015 per la versione 4.6)<\/li>\n\n\n\n<li>Fare clic sul file <code>.properties<\/code> o <code>.html<\/code> che si desidera aggiornare nella <a href=\"#detailedInstructions\">figura 1<\/a>,<\/li>\n\n\n\n<li>Seleziona le due caselle di controllo del numero di revisione corrispondente alla data della versione per il file aggiornato, scegliendo la data immediatamente precedente a una data di versione di Sweet Home 3D,<\/li>\n\n\n\n<li>Fare clic sul pulsante <em>Confronta<\/em>.<\/li>\n<\/ol>\n\n<p>L&#8217;ultimo clic mostrer\u00e0 le differenze tra le due versioni di quel file <code>.properties<\/code> (ad esempio, questo <a href=\"https:\/\/sourceforge.net\/p\/sweethome3d\/code\/6027\/tree\/\/trunk\/SweetHome3D\/src\/com\/eteks\/sweethome3d\/viewcontroller\/package.properties?diff=4806\" target=\"_blank\" rel=\"noopener\">link<\/a> mostrer\u00e0 le differenze tra la versione 4.6 e la versione 5.0 del file <code><a href=\"https:\/\/sourceforge.net\/p\/sweethome3d\/code\/HEAD\/log\/?path=\/trunk\/SweetHome3D\/src\/com\/eteks\/sweethome3d\/viewcontroller\/package.properties\" target=\"_blank\" rel=\"noopener\">com\/eteks\/sweethome3d\/viewcontroller\/package.properties<\/a><\/code>).<\/p>\n\n<p>Una volta trovate le differenze, aggiorna la tua traduzione, aggiungendo nuovi nomi di chiave se necessario, e rilascia una nuova versione della tua traduzione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Introduzione Parli una lingua straniera non ancora supportata in Sweet Home 3D e vorresti contribuire alla sua traduzione in quella lingua? Dalla versione 2.3, Sweet Home 3D supporta i file SH3L e questa guida ti insegner\u00e0 come creare un file di questo tipo da solo. Un file SH3L \u00e8 un file di lingua auto-installabile e<a href=\"https:\/\/test.sweethome3d.eu\/it\/guida-alla-traduzione\/\">Continue reading <span class=\"sr-only\">&#8220;Guida alla traduzione&#8221;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-resources.php","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-10165","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/test.sweethome3d.eu\/it\/wp-json\/wp\/v2\/pages\/10165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.sweethome3d.eu\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/test.sweethome3d.eu\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/test.sweethome3d.eu\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/test.sweethome3d.eu\/it\/wp-json\/wp\/v2\/comments?post=10165"}],"version-history":[{"count":1,"href":"https:\/\/test.sweethome3d.eu\/it\/wp-json\/wp\/v2\/pages\/10165\/revisions"}],"predecessor-version":[{"id":10166,"href":"https:\/\/test.sweethome3d.eu\/it\/wp-json\/wp\/v2\/pages\/10165\/revisions\/10166"}],"wp:attachment":[{"href":"https:\/\/test.sweethome3d.eu\/it\/wp-json\/wp\/v2\/media?parent=10165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}