{"id":10949,"date":"2025-09-18T11:53:10","date_gmt":"2025-09-18T11:53:10","guid":{"rendered":"https:\/\/test.sweethome3d.eu\/guida-per-lutente-di-sweet-home-3d\/"},"modified":"2026-01-28T21:29:31","modified_gmt":"2026-01-28T21:29:31","slug":"guida-per-lutente-di-sweet-home-3d","status":"publish","type":"page","link":"https:\/\/test.sweethome3d.eu\/it\/guida-per-lutente-di-sweet-home-3d\/","title":{"rendered":"Guida all&#8217;uso di Sweet Home 3D"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"before-starting\">Prima di iniziare<\/h2>\n\n<h3 class=\"wp-block-heading\" id=\"introduction\">Introduzione<\/h3>\n\n<p><a href=\"https:\/\/test.sweethome3d.eu\/it\/download\/\">Sweet Home 3D<\/a> \u00e8 un&#8217;applicazione gratuita di interior design che ti aiuta a posizionare i tuoi mobili su una planimetria 2D di una casa, con un&#8217;anteprima 3D.<\/p>\n\n<p>Disponibile all&#8217;indirizzo <a href=\"https:\/\/test.sweethome3d.eu\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/test.sweethome3d.eu\/,<\/a> questo programma \u00e8 rivolto a chi vuole progettare rapidamente i propri interni, sia che si tratti di un trasloco sia che si voglia semplicemente riprogettare la casa esistente. Numerose guide visive ti aiutano a disegnare la pianta della tua casa e a disporre i <a href=\"https:\/\/test.sweethome3d.eu\/it\/importazione-di-modelli-3d\/\" data-type=\"page\" data-id=\"432\">mobili<\/a>. Puoi <a href=\"#drawing-walls\">disegnare le pareti<\/a> delle tue stanze sull&#8217;immagine di una <a href=\"#importing-home-blueprint\">pianta esistente<\/a> e poi <a href=\"#adding-doors-windows-and-furniture\">trascinare<\/a> i mobili sulla pianta da un catalogo organizzato per categorie. Ogni modifica apportata alla pianta 2D viene aggiornata simultaneamente nella <a href=\"#creating-photos-of-the-3d-view\">vista 3D<\/a>, per mostrarti un rendering realistico del tuo layout.<\/p>\n\n<p>Questa guida ti mostra come creare una casa con <a href=\"https:\/\/test.sweethome3d.eu\/it\/download\/\">Sweet Home 3D<\/a> versione 7.5. Dopo aver descritto la sua interfaccia utente, imparerai come disegnare le pareti della tua casa e come disporre i mobili. L&#8217;esempio creato in questo tutorial \u00e8 disponibile su <a href=\"\/examples\/userGuideExample.sh3d\">sweethome3d.com<\/a> (3,2 MB).<\/p>\n\n<p>Per maggiori informazioni, puoi anche vedere i <a href=\"https:\/\/test.sweethome3d.eu\/it\/documentazione\/#video-tutorials\">video tutorial di Sweet Home 3D<\/a>, utilizzare l&#8217;aiuto di <a href=\"https:\/\/test.sweethome3d.eu\/\">Sweet Home 3D<\/a> accessibile dal pulsante <em>Aiuto<\/em> che si trova nella barra degli strumenti delle finestre di Sweet Home 3D e apprendere <a href=\"https:\/\/test.sweethome3d.eu\/it\/consigli-e-suggerimenti\/\">suggerimenti<\/a> avanzati.<\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-53acd6ed wp-block-group-is-layout-constrained\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccddbfd49&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccddbfd49\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"591\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-1024x591.png\" alt=\"Guida per gli utenti\" class=\"wp-image-4197 lazyload\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-1024x591.png 1024w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-300x173.png 300w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-156x90.png 156w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-768x443.png 768w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-1536x887.png 1536w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327.png 1562w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/591;\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">figura 1. Guida di Sweet Home 3D <\/figcaption><\/figure>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h3 class=\"wp-block-heading\" id=\"installation\">Installazione<\/h3>\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button btn-badge\" data-wce-label=\"wce_userguide_download_banner\"><a class=\"wp-block-button__link wp-element-button\" href=\"#download-app-store\">App store<\/a><\/div>\n<\/div>\n\n<p><a href=\"https:\/\/test.sweethome3d.eu\/it\/download\/\" data-type=\"page\" data-id=\"396\">Sweet Home 3D<\/a> pu\u00f2 essere eseguito su Windows, macOS, Linux, iOS e Android, ed \u00e8 tradotto in 29 diverse <a href=\"https:\/\/test.sweethome3d.eu\/it\/traduzioni\/\" data-type=\"page\" data-id=\"442\">lingue<\/a>.<br\/>A seconda del tuo sistema, usa le seguenti istruzioni per <a href=\"https:\/\/test.sweethome3d.eu\/it\/download\/\" data-type=\"page\" data-id=\"396\">scaricare Sweet Home 3D<\/a> e <a href=\"https:\/\/test.sweethome3d.eu\/it\/faq\/\" data-type=\"page\" data-id=\"422\">installarlo<\/a>:<\/p>\n\n<figure class=\"wp-block-flexible-table-block-table is-style-default table-border-bottom table-spacing-lg table-strong-semibold table-user-guide-installation\"><table class=\"\" style=\"width:100%;max-width:100%;border-width:0;border-collapse:separate;border-style:solid\"><tbody><tr><td style=\"border-width:0;border-color:#ffffff;width:110px\"><strong>Windows<\/strong>:<\/td><td>Scarica <a href=\"https:\/\/sourceforge.net\/projects\/sweethome3d\/files\/SweetHome3D\/SweetHome3D-7.5\/SweetHome3D-7.5-windows.exe\/download\" target=\"_blank\" rel=\"noopener\">https:\/\/sourceforge.net\/projects\/sweethome3d\/files\/SweetHome3D\/SweetHome3D-7.5\/SweetHome3D-7.5-windows.exe\/download<\/a> (84,9 MB), esegui il programma di installazione scaricato e segui le istruzioni della procedura guidata di installazione.<\/td><\/tr><tr><td><strong>macOS<\/strong>:<\/td><td>Scarica <a href=\"https:\/\/sourceforge.net\/projects\/sweethome3d\/files\/SweetHome3D\/SweetHome3D-7.5\/SweetHome3D-7.5-macosx.dmg\/download\" target=\"_blank\" rel=\"noopener\">https:\/\/sourceforge.net\/projects\/sweethome3d\/files\/SweetHome3D\/SweetHome3D-7.5\/SweetHome3D-7.5-macosx.dmg\/download<\/a> (83,6 MB), fai doppio clic sul file scaricato ed esegui l&#8217;<code>Sweet Home 3D<\/code> applicazione che si trova nella cartella aperta. Per installare <a href=\"https:\/\/test.sweethome3d.eu\/download.jsp\">Sweet Home 3D<\/a>, trascina e rilascia l&#8217;applicazione nella cartella di tua scelta.<\/td><\/tr><tr><td><strong>Linux<\/strong>: <\/td><td>Scarica <a href=\"https:\/\/sourceforge.net\/projects\/sweethome3d\/files\/SweetHome3D\/SweetHome3D-7.5\/SweetHome3D-7.5-linux-x64.tgz\/download\" target=\"_blank\" rel=\"noopener\">https:\/\/sourceforge.net\/projects\/sweethome3d\/files\/SweetHome3D\/SweetHome3D-7.5\/SweetHome3D-7.5-linux-x64.tgz\/download<\/a> (71,7 MB), decomprimi il file scaricato ed esegui l&#8217;<code>SweetHome3D<\/code> applicazione che si trova nella directory decompressa. Per installare <a href=\"https:\/\/test.sweethome3d.eu\/it\/download\/\" data-type=\"page\" data-id=\"396\">Sweet Home 3D<\/a>, sposta la directory decompressa in una di tua scelta.<\/td><\/tr><tr><td><strong>iOS \/ Android<\/strong>:&nbsp;<\/td><td>Scarica Sweet Home 3D Mobile dall&#8217;<a href=\"https:\/\/apps.apple.com\/app\/sweet-home-3d-mobile\/1178963471\" target=\"_blank\" rel=\"noopener\">App Store<\/a> di Apple e da <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.eteks.sweethome3d.mobile\" target=\"_blank\" rel=\"noopener\">Google Play<\/a>.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>Puoi anche modificare le tue case con <a href=\"\/online-manager\" data-type=\"page\" data-id=\"398\">Sweet Home 3D Online<\/a> su qualsiasi dispositivo che supporti WebGL. Le caratteristiche di questa versione sono simili a quelle della <a href=\"https:\/\/test.sweethome3d.eu\/it\/download\/\" data-type=\"page\" data-id=\"396\">versione scaricabile<\/a>, tranne che per il fatto che le tue case saranno automaticamente salvate sul server di questo sito web una volta effettuata <a href=\"\/support\/forum\/registermember?lang=en\">la registrazione<\/a>.  <\/p>\n\n<p>La <a href=\"https:\/\/test.sweethome3d.eu\/online-manager\/\" data-type=\"page\" data-id=\"398\">versione online<\/a> non ha alcuna barra dei menu, ma tutte le voci di menu della <a href=\"https:\/\/test.sweethome3d.eu\/it\/download\/\" data-type=\"page\" data-id=\"396\">versione scaricabile<\/a> sono raggiungibili dai suoi menu contestuali o dalla barra degli strumenti, ad eccezione dell&#8217;importazione di <a href=\"https:\/\/test.sweethome3d.eu\/it\/importazione-di-modelli-3d\/\" data-type=\"page\" data-id=\"432\">modelli 3D<\/a>, cos\u00ec come la creazione di foto e video.<\/p>\n\n<p><\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h3 class=\"wp-block-heading\" id=\"user-interface\">Interfaccia utente<\/h3>\n\n<p>Ogni finestra di <a href=\"https:\/\/test.sweethome3d.eu\/it\/download\/\" data-type=\"page\" data-id=\"396\">Sweet Home 3D<\/a> modifica l&#8217;interior design di una casa ed \u00e8 divisa in quattro riquadri ridimensionabili, con una barra degli strumenti nella parte superiore, come mostrato nella figura 2 (per la versione Mobile, vedi anche <a href=\"\/blog\/2023\/09\/06\/sweet_home_3d_mobile_app.html\" data-type=\"link\" data-id=\"\/blog\/2023\/09\/06\/sweet_home_3d_mobile_app.html\">questa pagina<\/a>).<\/p>\n\n<figure class=\"wp-block-flexible-table-block-table is-style-default table-border-bottom table-spacing-lg table-strong-semibold table-user-guide-user-interface\" style=\"font-style:normal;font-weight:500\"><table class=\"\" style=\"width:100%;max-width:100%;border-width:0;border-collapse:separate;border-style:solid\"><tbody><tr><td style=\"border-width:0;border-color:#ffffff\"><strong>1. Il catalogo dei <a href=\"https:\/\/test.sweethome3d.eu\/it\/importazione-di-modelli-3d\/\" data-type=\"page\" data-id=\"432\">mobili<\/a><\/strong><\/td><td>Questo catalogo, organizzato per categorie, contiene tutti i mobili e gli oggetti che puoi aggiungere al design della tua casa. Puoi visualizzare i mobili di una categoria cliccando sul triangolo accanto al suo nome.<\/td><\/tr><tr><td><strong>2. L&#8217;elenco dei mobili della casa<\/strong><\/td><td>Questo elenco contiene i mobili della tua casa, dove possono essere visualizzati il loro nome, le dimensioni e altre caratteristiche. Pu\u00f2 essere ordinato cliccando sul titolo di ogni colonna.<\/td><\/tr><tr><td><strong>3. La planimetria della casa<\/strong><\/td><td>Questo riquadro visualizza la tua casa vista dall&#8217;alto, su una griglia e circondata da righelli. In questo riquadro si disegnano le pareti della casa con il mouse e si dispongono i mobili.<\/td><\/tr><tr><td><strong>4. La vista 3D della casa<\/strong><\/td><td>Questo riquadro visualizza la tua casa in 3 dimensioni. Puoi vedere la tua casa in questo riquadro dall&#8217;alto o dal punto di vista di un visitatore virtuale.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group is-content-justification-center is-layout-constrained wp-container-core-group-is-layout-bde18b4e wp-block-group-is-layout-constrained\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccddc51f8&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccddc51f8\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"620\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-1-1024x620.png\" alt=\"Guida all'interfaccia utente\" class=\"wp-image-4230 lazyload\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/620;object-fit:cover\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-1-1024x620.png 1024w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-1-300x182.png 300w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-1-149x90.png 149w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-1-768x465.png 768w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-1-1536x930.png 1536w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-1.png 1562w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">figura 2. Riquadri di Sweet Home 3D <\/figcaption><\/figure>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group warning-banner is-layout-grid wp-container-core-group-is-layout-9649a0d9 wp-block-group-is-layout-grid\">\n<figure class=\"wp-block-image size-full is-resized wp-container-content-f67f277b\"><img decoding=\"async\" width=\"190\" height=\"190\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/11\/Frame-281.png\" alt=\"\" class=\"wp-image-786 lazyload\" style=\"--smush-placeholder-width: 190px; --smush-placeholder-aspect-ratio: 190\/190;width:130px\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/11\/Frame-281.png 190w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/11\/Frame-281-90x90.png 90w\" data-sizes=\"(max-width: 190px) 100vw, 190px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure>\n\n\n\n<p class=\"wp-container-content-f70bb71d\">Ogni riquadro pu\u00f2 avere il focus (cio\u00e8 ricevere input da tastiera) e alcune operazioni dipendono dal riquadro con il focus, riconoscibile dal rettangolo colorato che lo circonda; ad esempio, la planimetria della casa ha il focus nella figura 2. Per trasferire il focus a un altro riquadro, usa i tasti Tab e Maiusc + Tab, oppure clicca nel riquadro che dovrebbe ottenere il focus. <\/p>\n<\/div>\n\n<div class=\"wp-block-group warning-banner border-t-0 warning-img-lg is-layout-grid wp-container-core-group-is-layout-9649a0d9 wp-block-group-is-layout-grid\">\n<figure class=\"wp-block-image size-full is-resized wp-container-content-b04ba3db\"><img decoding=\"async\" width=\"414\" height=\"240\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-1.png\" alt=\"\" class=\"wp-image-4237 lazyload\" style=\"--smush-placeholder-width: 414px; --smush-placeholder-aspect-ratio: 414\/240;object-fit:cover;width:130px\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-1.png 414w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-1-300x174.png 300w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-1-155x90.png 155w\" data-sizes=\"(max-width: 414px) 100vw, 414px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure>\n\n\n\n<p class=\"wp-container-content-1ed81c1b\">Tutte le modifiche apportate nella planimetria della casa sono annullabili\/ripristinabili cliccando sui pulsanti Annulla e Ripristina nella barra degli strumenti. Non esitare a provare le varie operazioni proposte dal programma. <\/p>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\">Disegna pareti e crea planimetrie accurate<\/h2>\n\n<h3 class=\"wp-block-heading\" id=\"starting-a-new-home\">Iniziare una nuova casa<\/h3>\n\n<p>Prima di procedere oltre, visualizza la finestra di dialogo delle preferenze come mostrato nella figura 3, con la voce di menu <em>Sweet Home 3D &gt; Preferenze&#8230;<\/em> sotto macOS o la voce di menu <em>File &gt; Preferenze&#8230;<\/em> sotto altri sistemi. Controlla l&#8217;unit\u00e0 di misura predefinita utilizzata nel programma, lo spessore e l&#8217;altezza predefiniti delle pareti e altre preferenze. <br\/><\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-b5ae9130 wp-block-group-is-layout-constrained\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccddca1c7&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccddca1c7\" class=\"wp-block-image size-large is-resized wp-lightbox-container\"><img decoding=\"async\" width=\"711\" height=\"1024\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-2-711x1024.png\" alt=\"guida per gli utenti: Disegnare pareti e creare planimetrie accurate\" class=\"wp-image-4249 lazyload\" style=\"--smush-placeholder-width: 711px; --smush-placeholder-aspect-ratio: 711\/1024;aspect-ratio:0.6943430541697715;width:500px;height:auto\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-2-711x1024.png 711w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-2-208x300.png 208w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-2-62x90.png 62w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-2-768x1106.png 768w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-2-1066x1536.png 1066w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-2-1422x2048.png 1422w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-2.png 1562w\" data-sizes=\"(max-width: 711px) 100vw, 711px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">figura 3. Modifica delle preferenze <\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-group warning-banner border-t-0  warning-img-lg is-layout-grid wp-container-core-group-is-layout-9649a0d9 wp-block-group-is-layout-grid\">\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"414\" height=\"240\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-2-1.png\" alt=\"\" class=\"wp-image-4254 lazyload\" style=\"--smush-placeholder-width: 414px; --smush-placeholder-aspect-ratio: 414\/240;object-fit:cover;width:130px\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-2-1.png 414w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-2-1-300x174.png 300w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-2-1-155x90.png 155w\" data-sizes=\"(max-width: 414px) 100vw, 414px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure>\n\n\n\n<p class=\"wp-container-content-1ed81c1b\">Per creare una casa, usa semplicemente la casa predefinita creata all&#8217;avvio di Sweet Home 3D o clicca sul pulsante Nuova casa nella barra degli strumenti.<\/p>\n<\/div>\n\n<p>I passaggi suggeriti per la progettazione di una casa in <a href=\"https:\/\/test.sweethome3d.eu\/it\/download\/\">Sweet Home 3D<\/a> sono:<\/p>\n\n<ol class=\"wp-block-list default-ol pl-14\">\n<li><a href=\"#importing-home-blueprint\" data-type=\"internal\" data-id=\"#importingHomeBlueprint\">Importa la planimetria scansionata<\/a> della tua casa come immagine di sfondo della planimetria,<\/li>\n\n\n\n<li><a href=\"#drawing-walls\" data-type=\"internal\" data-id=\"#drawingWalls\">Disegna le pareti<\/a> su questa immagine di sfondo,<\/li>\n\n\n\n<li><a href=\"#editingWalls\" data-type=\"internal\" data-id=\"#editingWalls\">Modifica lo spessore, i colori e le texture delle pareti<\/a>,<\/li>\n\n\n\n<li><a href=\"#adding-doors-windows-and-furniture\" data-type=\"internal\" data-id=\"#addingFurniture\">Aggiungi porte e finestre<\/a> alla planimetria della tua casa e regola le loro dimensioni, per ottenere una vista realistica della tua casa vuota,<\/li>\n\n\n\n<li><a href=\"#adding-doors-windows-and-furniture\" data-type=\"internal\" data-id=\"#addingFurniture\">Aggiungi mobili<\/a> alla planimetria della tua casa, regola le loro dimensioni e posizione, eventualmente usando <a href=\"#nbspimporting-3d-models\" data-type=\"internal\" data-id=\"#importing3DModels\">modelli 3D importati<\/a>,<\/li>\n\n\n\n<li><a href=\"#drawingRooms\" data-type=\"internal\" data-id=\"#drawingRooms\">Disegna <\/a><a href=\"#drawing-rooms\">stanze<\/a> e cambia il colore o la texture del loro pavimento e del loro soffitto,<\/li>\n\n\n\n<li>Se la tua casa ha pi\u00f9 di un piano, <a href=\"#adding-levels\" data-type=\"internal\" data-id=\"#addingLevels\">aggiungi livelli<\/a> e scale che li collegano, e riavvia i primi sei passaggi per ogni livello,<\/li>\n\n\n\n<li><a href=\"#otherFeatures\" data-type=\"internal\" data-id=\"#otherFeatures\">Disegna dimensioni<\/a> e <a href=\"#adding-texts\" data-type=\"internal\" data-id=\"#addingTexts\">aggiungi testi<\/a> nella planimetria della tua casa per documentarla prima di <a href=\"#print\" data-type=\"internal\" data-id=\"#Printing\">stamparla<\/a>.<\/li>\n<\/ol>\n\n<p>Durante questi passaggi, probabilmente navigherai spesso nella vista 3D per <a href=\"#editing-3d-view\" data-type=\"internal\" data-id=\"#editing3DView\">cambiare il punto di vista<\/a> sulla tua disposizione.<\/p>\n\n<div class=\"wp-block-group warning-banner border-t-0  warning-img-lg is-layout-grid wp-container-core-group-is-layout-9649a0d9 wp-block-group-is-layout-grid\">\n<figure class=\"wp-block-image size-full is-resized wp-container-content-29dca9c1\"><img decoding=\"async\" width=\"414\" height=\"240\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-3-1.png\" alt=\"\" class=\"wp-image-4274 lazyload\" style=\"--smush-placeholder-width: 414px; --smush-placeholder-aspect-ratio: 414\/240;object-fit:cover;width:130px\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-3-1.png 414w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-3-1-300x174.png 300w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-3-1-155x90.png 155w\" data-sizes=\"(max-width: 414px) 100vw, 414px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure>\n\n\n\n<p class=\"wp-container-content-1ed81c1b\">A proposito, non dimenticare di salvare regolarmente il tuo progetto cliccando sul pulsante <em>Salva casa<\/em> (tranne che nella <a href=\"\/online-manager\/\" data-type=\"page\" data-id=\"398\">versione Online<\/a> dove la casa modificata viene salvata automaticamente). Un file Sweet Home 3D pu\u00f2 essere scambiato con altri utenti e pu\u00f2 contenere <a href=\"#nbspimporting-3d-models\" data-type=\"internal\" data-id=\"#importing3DModels\">modelli 3D importati<\/a> non presenti nel catalogo predefinito.<br\/><br\/>Puoi anche <a href=\"#creating-photos-of-the-3d-view\" data-type=\"internal\" data-id=\"#creatingPhotos\">creare immagini<\/a> della vista 3D in formato PNG, <a href=\"#creating-3d-videos\" data-type=\"internal\" data-id=\"#creatingVideos\">calcolare video 3D<\/a> da un percorso virtuale nella tua casa ed <a href=\"#export-to-obj-format\" data-type=\"internal\" data-id=\"#ExportingtoSVG\">esportare la vista 3D<\/a> della tua casa in formato OBJ + MTL.<\/p>\n<\/div>\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h3 class=\"wp-block-heading\" id=\"importing-home-blueprint\">Importazione della planimetria della casa<\/h3>\n\n<div class=\"wp-block-group warning-banner is-layout-grid wp-container-core-group-is-layout-9649a0d9 wp-block-group-is-layout-grid\">\n<figure class=\"wp-block-image size-full is-resized wp-container-content-1387b69e\"><img decoding=\"async\" width=\"190\" height=\"190\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/11\/Frame-281.png\" alt=\"\" class=\"wp-image-786 lazyload\" style=\"--smush-placeholder-width: 190px; --smush-placeholder-aspect-ratio: 190\/190;width:130px\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/11\/Frame-281.png 190w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/11\/Frame-281-90x90.png 90w\" data-sizes=\"(max-width: 190px) 100vw, 190px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure>\n\n\n\n<p class=\"wp-container-content-1ed81c1b\">Questo primo passo non \u00e8 obbligatorio ma velocizza il <a href=\"#drawing-walls\" data-type=\"internal\" data-id=\"#drawingWalls\">disegno delle pareti<\/a> di una casa esistente. Cerca quindi di trovare la planimetria della tua casa e scansionala, se non l&#8217;hai ancora fatto, assicurandoti che l&#8217;immagine sia ruotata correttamente. Non importare un file di grandi dimensioni in <a href=\"https:\/\/test.sweethome3d.eu\/it\/download\/\" data-type=\"page\" data-id=\"396\">Sweet Home 3D<\/a>, questa immagine deve essere un aiuto, non un&#8217;opera d&#8217;arte!<\/p>\n<\/div>\n\n<p>Scegli il menu <em>Planimetria &gt; Importa immagine di sfondo&#8230;<\/em> per visualizzare la procedura guidata che ti aiuta a scegliere e scalare un file immagine, come mostrato nella figura 4.<\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-53acd6ed wp-block-group-is-layout-constrained\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccddcf7a7&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccddcf7a7\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"829\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-3-1024x829.png\" alt=\"\" class=\"wp-image-4279 lazyload\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-3-1024x829.png 1024w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-3-300x243.png 300w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-3-111x90.png 111w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-3-768x621.png 768w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-3-1536x1243.png 1536w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-3.png 1562w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/829;\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">figura 4. Procedura guidata per l&#8217;importazione di immagini di sfondo <\/figcaption><\/figure>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<ol class=\"wp-block-list pl-14\">\n<li>Clicca su <em>Scegli immagine<\/em> e scegli la tua immagine nella finestra di dialogo del file. <a href=\"https:\/\/test.sweethome3d.eu\/it\/download\/\" data-type=\"page\" data-id=\"396\">Sweet Home 3D<\/a> supporta i formati BMP, JPEG, GIF o PNG. L&#8217;immagine scansionata utilizzata in questo tutorial \u00e8 disponibile su <a href=\"\/examples\/userGuideBluePrint.jpg\">sweethome3d.com<\/a><\/li>\n\n\n\n<li>Una volta caricata l&#8217;immagine, clicca su <em>Continua<\/em>.<\/li>\n\n\n\n<li>Definisci la scala dell&#8217;immagine spostando i punti finali della linea colorata disegnata nell&#8217;immagine, in modo che questa linea corrisponda a una lunghezza nota. Quindi digita la lunghezza reale di questa linea nel campo <em>Lunghezza della linea disegnata<\/em> e clicca su <em>Continua<\/em>. <\/li>\n\n\n\n<li>Definisci l&#8217;origine dell&#8217;immagine nella planimetria, cio\u00e8 il punto nell&#8217;immagine che corrisponde al punto (0, 0) nella planimetria della casa. Quindi clicca su <em>Fine<\/em>. <\/li>\n<\/ol>\n\n<p>Una volta chiusa la procedura guidata, la tua immagine apparir\u00e0 dietro la griglia della planimetria della casa alla scala scelta, come mostrato nella figura 5. Se hai scelto una scala o una posizione sbagliata, modificali scegliendo <em>Planimetria &gt; Modifica immagine di sfondo&#8230;<\/em> dal menu. <\/p>\n\n<p>Se hai un dispositivo iOS e non hai gi\u00e0 una planimetria da importare, l&#8217;app Metro semplifica la creazione di una in pochi minuti. Con pochi tocchi, puoi generare una planimetria accurata della tua casa: <\/p>\n\n<ol class=\"wp-block-list pl-14\">\n<li>Apri l&#8217;app e punta il telefono verso ogni angolo della stanza.<\/li>\n\n\n\n<li>Tocca per contrassegnare gli angoli man mano che procedi.<\/li>\n\n\n\n<li>Una volta contrassegnati tutti gli angoli, l&#8217;app genera una planimetria perfettamente scalata.<\/li>\n\n\n\n<li>Salva la planimetria come immagine sul tuo telefono e importala in Sweet Home 3d. Se usi Sweet Home 3d dal tuo computer, invia l&#8217;immagine al tuo computer e importala da l\u00ec. <\/li>\n<\/ol>\n\n<p>Tieni presente che Metro \u00e8 attualmente disponibile solo su iOS, ma la versione Android sar\u00e0 rilasciata a breve.<\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-53acd6ed wp-block-group-is-layout-constrained\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccddd2db0&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccddd2db0\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"854\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-4-1024x854.png\" alt=\"\" class=\"wp-image-4284 lazyload\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-4-1024x854.png 1024w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-4-300x250.png 300w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-4-108x90.png 108w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-4-768x640.png 768w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-4-1536x1280.png 1536w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-4.png 1562w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/854;\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">figura 5. Immagine di sfondo nel riquadro della planimetria della casa <\/figcaption><\/figure>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h3 class=\"wp-block-heading\" id=\"drawing-walls\">Disegno delle pareti<\/h3>\n\n<div class=\"wp-block-group warning-banner border-t-0  warning-img-lg is-layout-grid wp-container-core-group-is-layout-9649a0d9 wp-block-group-is-layout-grid\">\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"414\" height=\"240\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-4.png\" alt=\"\" class=\"wp-image-4288 lazyload\" style=\"--smush-placeholder-width: 414px; --smush-placeholder-aspect-ratio: 414\/240;object-fit:cover;width:130px\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-4.png 414w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-4-300x174.png 300w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-4-155x90.png 155w\" data-sizes=\"(max-width: 414px) 100vw, 414px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure>\n\n\n\n<p class=\"wp-container-content-1ed81c1b\">Per disegnare le pareti, clicca prima sul pulsante Crea pareti nella barra degli strumenti.<\/p>\n<\/div>\n\n<p>Clicca nella planimetria della casa nel punto iniziale della nuova parete, quindi clicca o fai doppio clic nella planimetria nel suo punto finale. Finch\u00e9 non fai doppio clic o premi il tasto <em>Esc<\/em>, ogni nuovo clic indica il punto opposto della parete corrente e il punto iniziale della parete successiva. <\/p>\n\n<div class=\"wp-block-group warning-banner border-t-0  warning-img-lg is-layout-grid wp-container-core-group-is-layout-9649a0d9 wp-block-group-is-layout-grid\">\n<figure class=\"wp-block-image size-full is-resized wp-container-content-29dca9c1\"><img decoding=\"async\" width=\"414\" height=\"240\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-5.png\" alt=\"\" class=\"wp-image-4293 lazyload\" style=\"--smush-placeholder-width: 414px; --smush-placeholder-aspect-ratio: 414\/240;object-fit:cover;width:130px\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-5.png 414w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-5-300x174.png 300w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-5-155x90.png 155w\" data-sizes=\"(max-width: 414px) 100vw, 414px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure>\n\n\n\n<p class=\"wp-container-content-1ed81c1b\">Per aiutarti a disegnare le pareti con precisione, usa il tooltip delle pareti, le linee di allineamento e cambia la scala della planimetria con i pulsanti <em>Zoom<\/em>. Puoi anche inserire la lunghezza e l&#8217;angolo della parete che viene creata dopo aver premuto il tasto <em>Invio<\/em> (funzionalit\u00e0 non disponibile nelle versioni <a href=\"\/online-manager\/\" data-type=\"page\" data-id=\"398\">Online<\/a> e Mobile). <\/p>\n<\/div>\n\n<p>Non prendere in considerazione porte e finestre mentre disegni le pareti, perch\u00e9 <a href=\"https:\/\/test.sweethome3d.eu\/it\/download\/\" data-type=\"page\" data-id=\"396\">Sweet Home 3D<\/a> calcoler\u00e0 automaticamente i fori nelle pareti dove posizionare le aperture. Come mostrato nella figura 6, le pareti vengono disegnate simultaneamente nella vista in pianta e nella vista 3D e puoi <a href=\"#editing-3d-view\" data-type=\"internal\" data-id=\"#editing3DView\">regolare il punto di vista<\/a> nella vista 3D in qualsiasi momento, muovendo il mouse con il tasto sinistro premuto.<\/p>\n\n<p><\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-53acd6ed wp-block-group-is-layout-constrained\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccddd7914&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccddd7914\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" width=\"962\" height=\"1024\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-5-962x1024.png\" alt=\"\" class=\"wp-image-4298 lazyload\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-5-962x1024.png 962w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-5-282x300.png 282w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-5-85x90.png 85w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-5-768x817.png 768w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-5-1444x1536.png 1444w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-5.png 1562w\" data-sizes=\"(max-width: 962px) 100vw, 962px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 962px; --smush-placeholder-aspect-ratio: 962\/1024;\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">figura 6. Disegno delle pareti <\/figcaption><\/figure>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group warning-banner is-layout-grid wp-container-core-group-is-layout-9649a0d9 wp-block-group-is-layout-grid\">\n<figure class=\"wp-block-image size-full is-resized wp-container-content-1387b69e\"><img decoding=\"async\" width=\"190\" height=\"190\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/11\/Frame-281.png\" alt=\"\" class=\"wp-image-786 lazyload\" style=\"--smush-placeholder-width: 190px; --smush-placeholder-aspect-ratio: 190\/190;width:130px\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/11\/Frame-281.png 190w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/11\/Frame-281-90x90.png 90w\" data-sizes=\"(max-width: 190px) 100vw, 190px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure>\n\n\n\n<p class=\"wp-container-content-1ed81c1b\">Per aiutarti a disegnare pareti parallele, l&#8217;angolo delle pareti sul pavimento \u00e8 un multiplo di 15\u00b0 per impostazione predefinita. Puoi annullare questo magnetismo disabilitando il magnetismo nella finestra di dialogo delle <a href=\"#starting-a-new-home\">preferenze<\/a> o tenendo premuto il tasto <em>Alt<\/em> durante il disegno sotto Windows, il tasto <em>cmd<\/em> sotto macOS o i tasti <em>Maiusc + Alt<\/em> sotto Linux. <\/p>\n<\/div>\n\n<h3 class=\"wp-block-heading\" id=\"editing-walls\">Modifica delle pareti<\/h3>\n\n<div class=\"wp-block-group warning-banner border-t-0  warning-img-lg is-layout-grid wp-container-core-group-is-layout-9649a0d9 wp-block-group-is-layout-grid\">\n<figure class=\"wp-block-image size-full is-resized wp-container-content-29dca9c1\"><img decoding=\"async\" width=\"414\" height=\"240\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-6.png\" alt=\"\" class=\"wp-image-4302 lazyload\" style=\"--smush-placeholder-width: 414px; --smush-placeholder-aspect-ratio: 414\/240;object-fit:cover;width:130px\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-6.png 414w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-6-300x174.png 300w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-6-155x90.png 155w\" data-sizes=\"(max-width: 414px) 100vw, 414px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure>\n\n\n\n<p class=\"wp-container-content-1ed81c1b\">Clicca sul pulsante <em>Seleziona<\/em> nella barra degli strumenti per terminare il <a href=\"#drawing-walls\">disegno delle pareti<\/a> e utilizzare gli strumenti disabilitati durante il disegno delle pareti.<br\/>Quando \u00e8 stata scelta la modalit\u00e0 <em>Seleziona<\/em>, puoi selezionare un oggetto nella pianta della tua casa cliccando su di esso. Puoi anche selezionare uno o pi\u00f9 oggetti disegnando un rettangolo di selezione intorno ad essi o cliccando su ciascuno di essi mentre premi il tasto <em>Shift<\/em>.<\/p>\n<\/div>\n\n<p>Per spostare le pareti selezionate (e altri oggetti) nella planimetria della casa, trascinale e rilasciale semplicemente, oppure usa i tasti freccia della tastiera. Quando <strong>una<\/strong> parete \u00e8 selezionata nella planimetria, puoi anche spostare il suo punto iniziale e finale con il mouse o dividerla in due pareti con la voce di menu <em>Planimetria &gt; Dividi parete<\/em>.<br\/>Fai doppio clic su una parete o scegli <em>Planimetria &gt; Modifica pareti&#8230;<\/em> dal menu per modificare l&#8217;insieme corrente di pareti selezionate con la finestra di dialogo delle pareti.<br\/>Come mostrato nella figura 7, questa finestra di dialogo ti aiuta a modificare i colori o le texture dei lati sinistro e destro delle pareti selezionate, e il loro spessore e la loro altezza. Se vuoi usare un&#8217;immagine di tua propriet\u00e0 come texture, clicca sul pulsante <em>Importa<\/em> e usa la procedura guidata di importazione della <a href=\"https:\/\/test.sweethome3d.eu\/it\/importazione-di-texture\/\" data-type=\"page\" data-id=\"961\">texture<\/a> che ti guider\u00e0.  <\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-94bc23d7 wp-block-group-is-layout-flex\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccdddc677&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccdddc677\" class=\"wp-block-image size-large wp-container-content-432d1f4f wp-lightbox-container\"><img decoding=\"async\" width=\"853\" height=\"1024\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-6-853x1024.png\" alt=\"\" class=\"wp-image-4303 lazyload\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-6-853x1024.png 853w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-6-250x300.png 250w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-6-75x90.png 75w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-6-768x922.png 768w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-6-1279x1536.png 1279w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-6.png 1562w\" data-sizes=\"(max-width: 853px) 100vw, 853px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 853px; --smush-placeholder-aspect-ratio: 853\/1024;\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">figura 7. Modifica degli attributi delle pareti <\/figcaption><\/figure>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\">Inserisci porte, finestre, mobili e personalizza ogni stanza<\/h2>\n\n<h3 class=\"wp-block-heading\" id=\"adding-doors-windows-and-furniture\">Aggiunta di porte, finestre e mobili<\/h3>\n\n<div class=\"wp-block-group alignwide warning-banner border-t-0  warning-img-lg is-layout-grid wp-container-core-group-is-layout-9649a0d9 wp-block-group-is-layout-grid\">\n<figure class=\"wp-block-image size-full is-resized wp-container-content-29dca9c1\"><img decoding=\"async\" width=\"414\" height=\"240\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-7.png\" alt=\"\" class=\"wp-image-4308 lazyload\" style=\"--smush-placeholder-width: 414px; --smush-placeholder-aspect-ratio: 414\/240;object-fit:cover;width:130px\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-7.png 414w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-7-300x174.png 300w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-7-155x90.png 155w\" data-sizes=\"(max-width: 414px) 100vw, 414px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure>\n\n\n\n<p class=\"wp-container-content-1ed81c1b\">Per aggiungere mobili alla tua casa, trascina e rilascia i <a href=\"https:\/\/test.sweethome3d.eu\/it\/importazione-di-modelli-3d\/\" data-type=\"page\" data-id=\"432\">mobili<\/a> dal catalogo alla planimetria della casa o all&#8217;elenco dei mobili, come mostrato nella figura 8, oppure seleziona un elemento nel catalogo e clicca sul pulsante <em>Aggiungi mobili<\/em> nella barra degli strumenti.<br\/>Gli elementi aggiunti alla casa sono selezionati e disegnati simultaneamente nell&#8217;elenco dei mobili, nella planimetria della casa e nella <a href=\"#editing-3d-view\" data-type=\"internal\" data-id=\"#editing3DView\">vista 3D<\/a>.<\/p>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-53acd6ed wp-block-group-is-layout-constrained\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccdde1308&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccdde1308\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"542\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-7-1024x542.png\" alt=\"\" class=\"wp-image-4309 lazyload\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-7-1024x542.png 1024w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-7-300x159.png 300w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-7-170x90.png 170w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-7-768x406.png 768w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-7-1536x812.png 1536w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-7.png 1562w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/542;\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">figura 8. Aggiunta di porte, finestre e mobili alla planimetria della casa <\/figcaption><\/figure>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>Aggiungi prima porte e finestre alla planimetria della tua casa per ottenere una vista realistica della tua casa vuota. Quando il magnetismo \u00e8 attivo, una porta o una finestra rilasciata su una parete viene automaticamente orientata e ridimensionata a seconda dell&#8217;orientamento e dello spessore di quella parete.<br\/>Quindi aggiungi <a href=\"https:\/\/test.sweethome3d.eu\/it\/importazione-di-modelli-3d\/\" data-type=\"page\" data-id=\"432\">mobili<\/a> e regola la loro posizione, angolo e dimensione. Quando il magnetismo \u00e8 attivo, un pezzo di <a href=\"https:\/\/test.sweethome3d.eu\/it\/importazione-di-modelli-3d\/\" data-type=\"page\" data-id=\"432\">mobile<\/a> viene automaticamente ruotato in modo che la sua faccia posteriore si trovi lungo la parete su cui hai rilasciato il cursore del mouse, e un pezzo rilasciato su uno pi\u00f9 grande verr\u00e0 elevato per apparire sulla sommit\u00e0 di quest&#8217;ultimo, se la sua elevazione predefinita \u00e8 a livello del pavimento.  <\/p>\n\n<p>Quando <strong>un<\/strong> pezzo \u00e8 selezionato nella planimetria, puoi cambiarne le dimensioni, l&#8217;elevazione o l&#8217;angolo con uno dei quattro indicatori che appaiono in ogni angolo del pezzo selezionato, come mostrato nella figura 9.<br\/><\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-53acd6ed wp-block-group-is-layout-constrained\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccdde427e&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccdde427e\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"704\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-8-1024x704.png\" alt=\"\" class=\"wp-image-4312 lazyload\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-8-1024x704.png 1024w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-8-300x206.png 300w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-8-131x90.png 131w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-8-768x528.png 768w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-8-1536x1056.png 1536w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-8.png 1562w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/704;\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">figura 9. Indicatori di un mobile selezionato <\/figcaption><\/figure>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<ol class=\"wp-block-list pl-14\">\n<li>L&#8217;indicatore di rotazione mostra l&#8217;angolo che puoi trascinare per ruotare il pezzo selezionato. Tieni premuto il tasto Alt per attivare\/disattivare il magnetismo di 15\u00b0 applicato durante la rotazione. <\/li>\n\n\n\n<li>L&#8217;indicatore di elevazione mostra l&#8217;angolo che puoi trascinare per cambiare l&#8217;elevazione dal pavimento del pezzo selezionato.<\/li>\n\n\n\n<li>L&#8217;indicatore di altezza mostra l&#8217;angolo che puoi trascinare per cambiare l&#8217;altezza del pezzo selezionato.<\/li>\n\n\n\n<li>L&#8217;indicatore di dimensione mostra l&#8217;angolo che puoi trascinare per cambiare la larghezza e la profondit\u00e0 del pezzo selezionato.<\/li>\n<\/ol>\n\n<p>\u00c8 anche possibile fare doppio clic su un elemento di arredo o scegliere <em>Arredamento &gt; Modifica&#8230;<\/em> dal menu per modificare l&#8217;insieme corrente di elementi selezionati con la finestra di dialogo dell&#8217;arredamento. Come mostrato nella figura 10, questa finestra di dialogo consente di modificare il nome dell&#8217;arredamento selezionato, l&#8217;angolo di rotazione, la posizione, l&#8217;elevazione dal pavimento, le dimensioni, il colore o la <a href=\"https:\/\/test.sweethome3d.eu\/it\/importazione-di-texture\/\" data-type=\"page\" data-id=\"435\">texture<\/a>, la visibilit\u00e0 e se la forma del modello 3D deve essere specchiata. Se gli oggetti selezionati contengono una o pi\u00f9 luci, questa finestra di dialogo consentir\u00e0 anche di modificarne la potenza, ma ci\u00f2 avr\u00e0 effetto solo ai due migliori livelli di qualit\u00e0 nel pannello <a href=\"#creating-photos-of-the-3d-view\" data-type=\"internal\" data-id=\"#creatingPhotos\">creazione foto<\/a>.  <\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-53acd6ed wp-block-group-is-layout-constrained\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccdde767f&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccdde767f\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"901\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-9-1024x901.png\" alt=\"\" class=\"wp-image-4315 lazyload\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-9-1024x901.png 1024w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-9-300x264.png 300w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-9-102x90.png 102w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-9-768x676.png 768w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-9-1536x1351.png 1536w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-9.png 1562w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/901;\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">figura 10. Modifica degli attributi dell&#8217;arredamento <\/figcaption><\/figure>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group warning-banner is-layout-grid wp-container-core-group-is-layout-9649a0d9 wp-block-group-is-layout-grid\">\n<figure class=\"wp-block-image size-full is-resized wp-container-content-962be591\"><img decoding=\"async\" width=\"190\" height=\"190\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/11\/Frame-281.png\" alt=\"\" class=\"wp-image-786 lazyload\" style=\"--smush-placeholder-width: 190px; --smush-placeholder-aspect-ratio: 190\/190;width:130px\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/11\/Frame-281.png 190w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/11\/Frame-281-90x90.png 90w\" data-sizes=\"(max-width: 190px) 100vw, 190px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure>\n\n\n\n<p class=\"wp-container-content-1ed81c1b\">L&#8217;arredamento invisibile non viene disegnato nella planimetria e nella vista 3D, ma apparir\u00e0 comunque nell&#8217;elenco degli arredi per consentirti di renderlo nuovamente visibile in seguito.<\/p>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group is-layout-grid wp-container-core-group-is-layout-baef362d wp-block-group-is-layout-grid\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio embed-responsive wp-container-content-1b8dee80\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Sweet Home 3D Tutorial - How to customize furniture\" width=\"500\" height=\"281\" data-src=\"https:\/\/www.youtube.com\/embed\/5Ni5zE4q5kk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio embed-responsive\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Sweet Home 3D Tutorial - How to combine models together\" width=\"500\" height=\"281\" data-src=\"https:\/\/www.youtube.com\/embed\/sljp8C4WwGA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio embed-responsive wp-container-content-5e2576f9\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Sweet Home 3D Tutorial - How to create new furniture\" width=\"500\" height=\"281\" data-src=\"https:\/\/www.youtube.com\/embed\/4zEG8dqNy6w?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe>\n<\/div><\/figure>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h3 class=\"wp-block-heading\" id=\"drawing-rooms\">Disegno di stanze<\/h3>\n\n<p><\/p>\n\n<div class=\"wp-block-group alignwide  warning-banner border-t-0 warning-img-lg is-layout-grid wp-container-core-group-is-layout-9649a0d9 wp-block-group-is-layout-grid\">\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"414\" height=\"240\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-8.png\" alt=\"\" class=\"wp-image-4323 lazyload\" style=\"--smush-placeholder-width: 414px; --smush-placeholder-aspect-ratio: 414\/240;object-fit:cover;width:130px\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-8.png 414w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-8-300x174.png 300w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-8-155x90.png 155w\" data-sizes=\"(max-width: 414px) 100vw, 414px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure>\n\n\n\n<p class=\"wp-container-content-1ed81c1b\">Per disegnare stanze, fai prima clic sul pulsante Crea stanze.<\/p>\n<\/div>\n\n<p>Crea una nuova stanza o una nuova superficie nella planimetria usando uno dei seguenti metodi:<\/p>\n\n<ul class=\"wp-block-list pl-14\">\n<li>fai clic su ogni angolo della stanza, quindi fai doppio clic sull&#8217;ultimo punto o premi il tasto <em>Esc<\/em> dopo aver aggiunto l&#8217;ultimo punto,<\/li>\n\n\n\n<li>fai doppio clic in un punto qualsiasi all&#8217;interno di una superficie <strong>chiusa<\/strong> esistente (ovvero circondata da <a href=\"#drawing-walls\" data-type=\"internal\" data-id=\"#drawingWalls\">muri<\/a>), come mostrato nella figura 12.<br\/><\/li>\n<\/ul>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-53acd6ed wp-block-group-is-layout-constrained\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccddebbc5&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccddebbc5\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"644\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-11-1024x644.png\" alt=\"\" class=\"wp-image-4327 lazyload\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-11-1024x644.png 1024w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-11-300x189.png 300w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-11-143x90.png 143w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-11-768x483.png 768w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-11-1536x966.png 1536w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-11.png 1562w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/644;\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">figura 12. Creazione con un doppio clic di una stanza che include un mezzo gradino <\/figcaption><\/figure>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group warning-banner is-layout-grid wp-container-core-group-is-layout-9649a0d9 wp-block-group-is-layout-grid\">\n<figure class=\"wp-block-image size-full is-resized wp-container-content-422d1810\"><img decoding=\"async\" width=\"190\" height=\"190\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/11\/Frame-281.png\" alt=\"\" class=\"wp-image-786 lazyload\" style=\"--smush-placeholder-width: 190px; --smush-placeholder-aspect-ratio: 190\/190;width:130px\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/11\/Frame-281.png 190w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/11\/Frame-281-90x90.png 90w\" data-sizes=\"(max-width: 190px) 100vw, 190px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure>\n\n\n\n<p class=\"wp-container-content-1ed81c1b\"><a href=\"#drawing-walls\">Disegna prima le pareti<\/a> e <a href=\"#adding-doors-windows-and-furniture\">aggiungi le porte<\/a>, prima di disegnare le stanze. Utilizzando questo metodo, potrai creare stanze molto pi\u00f9 velocemente facendo doppio clic su ogni superficie che corrisponde a una stanza della tua casa. Nota anche che una stanza creata con un doppio clic includer\u00e0 la mezza porta di ogni porta posizionata sulle sue pareti. Questa funzione garantisce che le stanze si uniscano correttamente nella <a href=\"#editing-3d-view\" data-type=\"internal\" data-id=\"#editing3DView\">vista 3D<\/a> quando si aprono le porte tra le stanze. <\/p>\n<\/div>\n\n<p>Una volta creata una stanza, puoi modificarne il nome, il colore o la texture del pavimento e del soffitto, scegliendo <em>Piano &gt; Modifica stanze&#8230;<\/em> dal menu, come mostrato nella figura 13.<\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-53acd6ed wp-block-group-is-layout-constrained\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccddef00b&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccddef00b\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"569\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-12-1024x569.png\" alt=\"\" class=\"wp-image-4332 lazyload\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-12-1024x569.png 1024w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-12-300x167.png 300w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-12-162x90.png 162w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-12-768x427.png 768w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-12-1536x854.png 1536w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-12.png 1562w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/569;\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">figura 13. Modifica degli attributi della stanza <\/figcaption><\/figure>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>Quando \u00e8 selezionata <strong>una<\/strong> stanza, puoi anche spostare ciascuno dei suoi punti con il mouse in modalit\u00e0 <em>Seleziona<\/em> e modificare la posizione della sua area e del suo nome con gli indicatori disegnati sotto i testi.<\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h3 class=\"wp-block-heading\" id=\"adding-levels\">Aggiunta di livelli<\/h3>\n\n<p>Se la tua casa ha pi\u00f9 di un livello o di una storia, puoi <a href=\"https:\/\/test.sweethome3d.eu\/it\/documentazione\/#video-tutorials\" data-type=\"internal\" data-id=\"#videoTutorial\">creare i livelli aggiuntivi<\/a> scegliendo <em>Piano &gt; Livelli &gt; Aggiungi livello<\/em> dal menu o cliccando sulla scheda <strong>+<\/strong> che appare quando una casa ha pi\u00f9 di un livello. Ogni livello \u00e8 rappresentato da una scheda visualizzata nella parte superiore della vista in pianta e utilizzata per selezionare il livello in cui verranno aggiunti nuovi muri, mobili e altri oggetti.<\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-53acd6ed wp-block-group-is-layout-constrained\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccddf2904&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccddf2904\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"467\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-13-1024x467.png\" alt=\"\" class=\"wp-image-4338 lazyload\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-13-1024x467.png 1024w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-13-300x137.png 300w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-13-197x90.png 197w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-13-768x350.png 768w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-13-1536x700.png 1536w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-13.png 1562w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/467;\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">figura 14. Nuovo livello che mostra in colore chiaro i muri e i soffitti del livello inferiore <\/figcaption><\/figure>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>Come mostrato nella figura 14, i muri e i soffitti del livello inferiore vengono visualizzati con un colore chiaro nella vista della planimetria per aiutarti a utilizzare pi\u00f9 facilmente gli strumenti di disegno di muri o stanze. Se necessario, puoi anche copiare\/incollare alcuni oggetti da un altro livello al livello selezionato.<br\/>L&#8217;elevazione, l&#8217;altezza e lo spessore del pavimento predefiniti di ogni livello possono essere modificati facendo doppio clic sulla sua scheda o scegliendo <em>Piano &gt; Livelli &gt; Modifica livello&#8230;<\/em> dal menu. <\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-94bc23d7 wp-block-group-is-layout-flex\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccde01947&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccde01947\" class=\"wp-block-image size-large wp-container-content-432d1f4f wp-lightbox-container\"><img decoding=\"async\" width=\"867\" height=\"1024\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-14-867x1024.png\" alt=\"\" class=\"wp-image-4340 lazyload\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-14-867x1024.png 867w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-14-254x300.png 254w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-14-76x90.png 76w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-14-768x907.png 768w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-14-1301x1536.png 1301w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-14.png 1562w\" data-sizes=\"(max-width: 867px) 100vw, 867px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 867px; --smush-placeholder-aspect-ratio: 867\/1024;\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">figura 15. Modifica degli attributi del livello <\/figcaption><\/figure>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>Come mostrato nella figura 15, il pannello di modifica del livello mostra anche una tabella che descrive tutti i livelli di una casa per aiutarti a scegliere i valori giusti rispetto ad altri livelli. Per creare livelli sotterranei, immetti un&#8217;elevazione negativa. L&#8217;altezza del livello viene utilizzata per calcolare l&#8217;elevazione dei soffitti del livello modificato.  <\/p>\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-53acd6ed wp-block-group-is-layout-constrained\">\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Sweet Home 3D Tutorial: Layer Control Walkthrough\" width=\"500\" height=\"281\" data-src=\"https:\/\/www.youtube.com\/embed\/7c5OMgbHFUs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe>\n<\/div><\/figure>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\">Visualizza i progetti in 2D e 3D<\/h2>\n\n<h3 class=\"wp-block-heading editing-3d-view\" id=\"editing-3d-view\">Modifica della vista 3D<\/h3>\n\n<p>In qualsiasi momento durante il disegno della tua casa, puoi modificare il punto di vista utilizzato nella vista 3D. Sono disponibili due diversi modi di visualizzare la casa, la modalit\u00e0 selezionata predefinita impostata con il menu <em>Vista 3D &gt; Vista aerea<\/em> e l&#8217;altra modalit\u00e0 impostata con <em>Vista 3D &gt; Visita virtuale<\/em>. In entrambe le modalit\u00e0, puoi utilizzare il mouse o le frecce della tastiera per modificare il punto di vista corrente, come mostrato nelle figure 16 e 17.  <\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-94bc23d7 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-full wp-container-content-432d1f4f\"><img decoding=\"async\" width=\"761\" height=\"496\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-5-1.png\" alt=\"\" class=\"wp-image-4347 lazyload\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-5-1.png 761w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-5-1-300x196.png 300w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-5-1-138x90.png 138w\" data-sizes=\"(max-width: 761px) 100vw, 761px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 761px; --smush-placeholder-aspect-ratio: 761\/496;\" \/><figcaption class=\"wp-element-caption\">figura 16. Azioni del mouse e della tastiera in modalit\u00e0 vista aerea <\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full wp-container-content-432d1f4f\"><img decoding=\"async\" width=\"761\" height=\"496\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-6-1.png\" alt=\"\" class=\"wp-image-4348 lazyload\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-6-1.png 761w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-6-1-300x196.png 300w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-6-1-138x90.png 138w\" data-sizes=\"(max-width: 761px) 100vw, 761px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 761px; --smush-placeholder-aspect-ratio: 761\/496;\" \/><figcaption class=\"wp-element-caption\">figura 17. Azioni del mouse e della tastiera in modalit\u00e0 visita virtuale <\/figcaption><\/figure>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>Quando \u00e8 selezionata la modalit\u00e0 <em>Visita virtuale<\/em>, nella planimetria viene disegnato anche un visitatore virtuale visto dall&#8217;alto. La sua posizione e il suo angolo vengono aggiornati simultaneamente nella planimetria e nella vista 3D a ogni movimento del visitatore. Questo visitatore virtuale \u00e8 circondato da quattro indicatori, come mostrato nella figura 18.  <\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-53acd6ed wp-block-group-is-layout-constrained\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccde06fcb&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccde06fcb\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"759\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-15-1024x759.png\" alt=\"\" class=\"wp-image-4351 lazyload\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-15-1024x759.png 1024w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-15-300x222.png 300w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-15-121x90.png 121w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-15-768x569.png 768w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-15-1536x1139.png 1536w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-15.png 1562w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/759;\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">figura 18. Indicatori del visitatore virtuale <\/figcaption><\/figure>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<ol class=\"wp-block-list pl-14\">\n<li>L&#8217;<strong>indicatore dell&#8217;angolo della testa<\/strong> mostra l&#8217;angolo che puoi modificare per spostare la testa del visitatore verso l&#8217;alto o verso il basso.<\/li>\n\n\n\n<li>L&#8217;<strong>indicatore del campo visivo<\/strong> mostra l&#8217;angolo attualmente visualizzato nella vista 3D.<\/li>\n\n\n\n<li>L&#8217;<strong>indicatore dell&#8217;angolo del corpo<\/strong> mostra l&#8217;angolo che puoi modificare per spostare il corpo del visitatore verso sinistra o verso destra.<\/li>\n\n\n\n<li>L&#8217;<strong>indicatore dell&#8217;elevazione degli occhi<\/strong> mostra il punto che puoi trascinare per spostare verso l&#8217;alto o verso il basso il punto di vista del visitatore.<\/li>\n<\/ol>\n\n<p>Puoi anche scegliere <em>Vista 3D &gt; Modifica vista 3D&#8230;<\/em> dal menu per modificare il colore o la texture del terreno e del cielo, la luminosit\u00e0 della luce e la trasparenza dei muri, come mostrato nella figura 19.<\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-94bc23d7 wp-block-group-is-layout-flex\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccde09e5b&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccde09e5b\" class=\"wp-block-image size-large wp-container-content-432d1f4f wp-lightbox-container\"><img decoding=\"async\" width=\"1012\" height=\"1024\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-16-1012x1024.png\" alt=\"\" class=\"wp-image-4354 lazyload\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-16-1012x1024.png 1012w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-16-297x300.png 297w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-16-89x90.png 89w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-16-768x777.png 768w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-16-1519x1536.png 1519w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-16.png 1562w\" data-sizes=\"(max-width: 1012px) 100vw, 1012px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1012px; --smush-placeholder-aspect-ratio: 1012\/1024;\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">figura 19. Modifica degli attributi della vista 3D <\/figcaption><\/figure>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>Dopo aver modificato i colori del terreno e del cielo, la figura 20 mostra due schermate della vista 3D della <a href=\"\/examples\/userGuideExample.sh3d\">casa progettata in questo tutorial<\/a>.<\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-53acd6ed wp-block-group-is-layout-constrained\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccde0cb96&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccde0cb96\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"468\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-17-1024x468.png\" alt=\"\" class=\"wp-image-4355 lazyload\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-17-1024x468.png 1024w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-17-300x137.png 300w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-17-197x90.png 197w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-17-768x351.png 768w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-17-1536x702.png 1536w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-17.png 1562w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/468;\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">figura 20. Vista aerea e visita virtuale <\/figcaption><\/figure>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h3 class=\"wp-block-heading creating-photos-of-the-3d-view\" id=\"creating-photos-of-the-3d-view\">Creazione di foto della vista 3D<\/h3>\n\n<div class=\"wp-block-group alignwide warning-banner border-t-0  warning-img-lg is-layout-grid wp-container-core-group-is-layout-9649a0d9 wp-block-group-is-layout-grid\">\n<figure class=\"wp-block-image size-full is-resized wp-container-content-29dca9c1\"><img decoding=\"async\" width=\"414\" height=\"240\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-9.png\" alt=\"\" class=\"wp-image-4356 lazyload\" style=\"--smush-placeholder-width: 414px; --smush-placeholder-aspect-ratio: 414\/240;object-fit:cover;width:130px\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-9.png 414w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-9-300x174.png 300w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-9-155x90.png 155w\" data-sizes=\"(max-width: 414px) 100vw, 414px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure>\n\n\n\n<p class=\"wp-container-content-1ed81c1b\">Fai clic sullo strumento <em>Crea foto&#8230;<\/em> per creare un&#8217;immagine della <a href=\"#editing-3d-view\">vista 3D<\/a> con le dimensioni e le proporzioni che preferisci e salvarla in un file in formato PNG (funzionalit\u00e0 non disponibile nelle versioni <a href=\"\/online-manager\/\" data-type=\"page\" data-id=\"398\">Online<\/a> e Mobile).<\/p>\n<\/div>\n\n<p>Come mostrato nella figura 24, il pannello utilizzato per creare foto consente anche di scegliere il livello di qualit\u00e0 dell&#8217;immagine creata. Con un livello di qualit\u00e0 veloce, l&#8217;immagine creata avr\u00e0 lo stesso aspetto della <a href=\"#editing-3d-view\">vista 3D<\/a>, mentre con il miglior livello di qualit\u00e0, l&#8217;immagine sar\u00e0 pi\u00f9 fotorealistica. Ai due migliori livelli di qualit\u00e0, puoi gestire l&#8217;illuminazione dell&#8217;immagine aggiungendo luci a un diverso livello di potenza o modificando l&#8217;ora. Puoi anche scegliere il motore di rendering utilizzato per calcolare l&#8217;immagine, sapendo che il renderer <em>YafaRay<\/em> generalmente funziona pi\u00f9 velocemente del renderer predefinito <em>SunFlow<\/em>.   <\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-94bc23d7 wp-block-group-is-layout-flex\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccde1167d&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccde1167d\" class=\"wp-block-image size-large wp-container-content-432d1f4f wp-lightbox-container\"><img decoding=\"async\" width=\"959\" height=\"1024\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-19-959x1024.png\" alt=\"\" class=\"wp-image-4360 lazyload\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-19-959x1024.png 959w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-19-281x300.png 281w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-19-84x90.png 84w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-19-768x820.png 768w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-19-1438x1536.png 1438w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-19.png 1562w\" data-sizes=\"(max-width: 959px) 100vw, 959px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 959px; --smush-placeholder-aspect-ratio: 959\/1024;\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">figura 24. Creazione foto <\/figcaption><\/figure>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group warning-banner is-layout-grid wp-container-core-group-is-layout-9649a0d9 wp-block-group-is-layout-grid\">\n<figure class=\"wp-block-image size-full is-resized wp-container-content-1387b69e\"><img decoding=\"async\" width=\"190\" height=\"190\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/11\/Frame-281.png\" alt=\"\" class=\"wp-image-786 lazyload\" style=\"--smush-placeholder-width: 190px; --smush-placeholder-aspect-ratio: 190\/190;width:130px\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/11\/Frame-281.png 190w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/11\/Frame-281-90x90.png 90w\" data-sizes=\"(max-width: 190px) 100vw, 190px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure>\n\n\n\n<p class=\"wp-container-content-1ed81c1b\">Il calcolo di un&#8217;immagine al miglior livello di qualit\u00e0 pu\u00f2 richiedere molto tempo a seconda della tua casa e della potenza del tuo computer. Tuttavia, tieni presente che puoi comunque modificare la tua casa durante questo calcolo. Per motivi tecnici, \u00e8 possibile aprire un solo pannello Crea foto alla volta.  <\/p>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h3 class=\"wp-block-heading creating-3d-videos\" id=\"creating-3d-videos\">Creazione di video 3D<\/h3>\n\n<div class=\"wp-block-group alignwide warning-banner border-t-0  warning-img-lg is-layout-grid wp-container-core-group-is-layout-9649a0d9 wp-block-group-is-layout-grid\">\n<figure class=\"wp-block-image size-full is-resized wp-container-content-29dca9c1\"><img decoding=\"async\" width=\"414\" height=\"240\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-10.png\" alt=\"\" class=\"wp-image-4362 lazyload\" style=\"--smush-placeholder-width: 414px; --smush-placeholder-aspect-ratio: 414\/240;object-fit:cover;width:130px\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-10.png 414w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-10-300x174.png 300w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-10-155x90.png 155w\" data-sizes=\"(max-width: 414px) 100vw, 414px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure>\n\n\n\n<p class=\"wp-container-content-1ed81c1b\">Clicca sullo strumento <em>Crea video&#8230;<\/em> per visualizzare il riquadro utilizzato per creare un video da un percorso virtuale nella <a href=\"#editing-3d-view\">vista 3D<\/a> (funzione non disponibile nelle versioni <a href=\"\/online-manager\/\" data-type=\"page\" data-id=\"398\">Online<\/a> e Mobile). Come mostra la figura 25, questo pannello ti permette di scegliere il formato del video e la sua qualit\u00e0 in modo simile al <a href=\"#creating-photos-of-the-3d-view\">pannello di creazione delle foto<\/a>.<br\/><\/p>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-94bc23d7 wp-block-group-is-layout-flex\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccde15b24&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccde15b24\" class=\"wp-block-image size-large wp-container-content-432d1f4f wp-lightbox-container\"><img decoding=\"async\" width=\"854\" height=\"1024\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-20-854x1024.png\" alt=\"\" class=\"wp-image-4364 lazyload\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-20-854x1024.png 854w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-20-250x300.png 250w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-20-75x90.png 75w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-20-768x920.png 768w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-20-1282x1536.png 1282w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-20.png 1562w\" data-sizes=\"(max-width: 854px) 100vw, 854px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 854px; --smush-placeholder-aspect-ratio: 854\/1024;\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">figura 25. Creazione video <\/figcaption><\/figure>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>Per creare un video, scegli nella vista 3D la posizione iniziale della videocamera e fai clic sul pulsante rosso nel pannello di creazione video. Quindi spostati nella vista 3D nella posizione successiva della videocamera e fai di nuovo clic sul pulsante rosso. Ripeti questi passaggi per ogni posizione in cui la telecamera deve passare durante il video.<br\/>Ogni volta che fai clic sul pulsante rosso, viene aggiunto un nuovo punto nel pannello di creazione video per mostrarti il percorso della telecamera. Poich\u00e9 Sweet Home 3D tiene conto anche dell&#8217;elevazione verticale della telecamera, dei suoi 2 angoli di rotazione e del suo campo visivo, puoi creare tutti i tipi di animazioni.<br\/>Una volta che il percorso creato \u00e8 soddisfacente, fai clic sul pulsante <em>Crea<\/em> per avviare il calcolo dei fotogrammi del video, quindi, una volta terminato questo calcolo, fai clic sul pulsante <em>Salva&#8230;<\/em> per salvare il video in un file Quicktime. Puoi visualizzare questo video con diversi strumenti come <a href=\"https:\/\/www.videolan.org\/\" target=\"_blank\" rel=\"noopener\">VLC<\/a> o transcodificarlo in un altro formato. Le figure 26 e 27 mostrano due video calcolati dal percorso mostrato nella figura 25 e transcodificati in formato MPEG-4:     <\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-94bc23d7 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-video video-card-2\"><video height=\"1080\" style=\"aspect-ratio: 1920 \/ 1080;\" width=\"1920\" autoplay=\"\" loop=\"\" muted=\"\" poster=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/CleanShot-2025-10-20-at-17.21.03@2x-1-1.png\" src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Loft_last_3dquality.mp4\" playsinline=\"\"><\/video><figcaption class=\"wp-element-caption\">figura 26. Video con la stessa qualit\u00e0 della vista 3D <\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-video video-card-2\"><video height=\"1080\" style=\"aspect-ratio: 1920 \/ 1080;\" width=\"1920\" autoplay=\"\" loop=\"\" muted=\"\" poster=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/CleanShot-2025-10-20s-at-17.21.03@2x-1-1.png\" src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Loft_last_floor1.mp4\" playsinline=\"\"><\/video><figcaption class=\"wp-element-caption\">figura 27. Video alla migliore qualit\u00e0 <\/figcaption><\/figure>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group warning-banner is-layout-grid wp-container-core-group-is-layout-9649a0d9 wp-block-group-is-layout-grid\">\n<figure class=\"wp-block-image size-full is-resized wp-container-content-66c62f5e\"><img decoding=\"async\" width=\"190\" height=\"190\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/11\/Frame-281.png\" alt=\"\" class=\"wp-image-786 lazyload\" style=\"--smush-placeholder-width: 190px; --smush-placeholder-aspect-ratio: 190\/190;width:130px\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/11\/Frame-281.png 190w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/11\/Frame-281-90x90.png 90w\" data-sizes=\"(max-width: 190px) 100vw, 190px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure>\n\n\n\n<p class=\"wp-container-content-1ed81c1b\">Utilizza i pulsanti di riproduzione per controllare approssimativamente il percorso della telecamera nella vista 3D, perch\u00e9 il calcolo di un video pu\u00f2 richiedere da minuti a ore a seconda della tua casa, della qualit\u00e0 che hai scelto e della potenza del tuo computer.<\/p>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Sweet Home 3D Tutorial - How to create a video rendering\" width=\"500\" height=\"281\" data-src=\"https:\/\/www.youtube.com\/embed\/W_ExaiIvSHU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe>\n<\/div><\/figure>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\">Importa ed esporta<\/h2>\n\n<h3 class=\"wp-block-heading\" id=\"export-to-obj-format\">Esportazione in formato OBJ<\/h3>\n\n<p>Se vuoi riutilizzare la tua casa in un software 3D come <a href=\"https:\/\/www.blender.org\/\" target=\"_blank\" rel=\"noopener\">Blender<\/a> o <a href=\"https:\/\/aoi.sourceforge.net\/\" target=\"_blank\" rel=\"noopener\">Art of Illusion<\/a> per migliorarne il <a href=\"#creating-photos-of-the-3d-view\" data-type=\"internal\" data-id=\"#creatingPhotos\">rendering<\/a>, ad esempio, scegli la <em>vista 3D &gt; Esporta in formato OBJ&#8230;<\/em> dal menu e importa il file OBJ generato in questi software (funzione non disponibile nelle versioni <a href=\"\/online-manager\/\" data-type=\"page\" data-id=\"398\">Online<\/a> e Mobile). Questa voce di menu scriver\u00e0 nel file OBJ selezionato la descrizione di tutti gli oggetti visualizzati nella <a href=\"#editing-3d-view\" data-type=\"internal\" data-id=\"#editing3DView\">vista 3D<\/a>, creer\u00e0 un file MTL che ne descrive il colore e infine salver\u00e0 le immagini delle texture che hai utilizzato. La figura 28 mostra un rendering realizzato in Blender dopo l&#8217;aggiunta di alcune luci nella scena.<\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-53acd6ed wp-block-group-is-layout-constrained\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccde1d05e&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccde1d05e\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"733\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-21-1024x733.png\" alt=\"\" class=\"wp-image-4369 lazyload\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-21-1024x733.png 1024w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-21-300x215.png 300w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-21-126x90.png 126w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-21-768x550.png 768w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-21-1536x1099.png 1536w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-21.png 1562w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/733;\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">figura 28. Rendering di una casa esportata in Blender <\/figcaption><\/figure>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h3 class=\"wp-block-heading\" id=\"nbspimporting-3d-models\"> Importazione di modelli 3D<\/h3>\n\n<p>Se un mobile o un oggetto non \u00e8 presente nel catalogo di <a href=\"https:\/\/test.sweethome3d.eu\/it\/download\/\" data-type=\"page\" data-id=\"396\">Sweet Home 3D<\/a>, puoi importare un file <a href=\"https:\/\/test.sweethome3d.eu\/it\/importazione-di-modelli-3d\/\" data-type=\"page\" data-id=\"432\">di modello 3D<\/a> e utilizzarlo nella tua casa (funzione non disponibile nella <a href=\"https:\/\/test.sweethome3d.eu\/online-manager\/\" data-type=\"page\" data-id=\"398\">versione online<\/a>). All&#8217;indirizzo <a href=\"https:\/\/test.sweethome3d.eu\/it\/modelli-3d-gratuiti\/\" data-type=\"page\" data-id=\"4869\">https:\/\/test.sweethome3d.eu\/freeModels.jsp<\/a> \u00e8 possibile scaricare pi\u00f9 di 1600 modelli gratuiti progettati dai collaboratori, ma puoi anche scaricare modelli da <a href=\"https:\/\/test.sweethome3d.eu\/it\/importazione-di-modelli-3d\/#other-web-sites-with-3d-models\">altri siti web<\/a> o creare i tuoi modelli con software come <a href=\"https:\/\/www.blender.org\/\" target=\"_blank\" rel=\"noopener\">Blender<\/a> o <a href=\"https:\/\/aoi.sourceforge.net\/\" target=\"_blank\" rel=\"noopener\">Art of Illusion<\/a>. <a href=\"https:\/\/test.sweethome3d.eu\/it\/download\/\" data-type=\"page\" data-id=\"396\">Sweet Home 3D<\/a> supporta file di modelli 3D in formato OBJ, DAE, 3DS, file ZIP contenenti file di questo tipo e file KMZ.<\/p>\n\n<p>Puoi anche <a href=\"#download\" data-type=\"internal\" data-id=\"#download\">scaricare la versione completa<\/a> con oltre 10.000 <a href=\"https:\/\/test.sweethome3d.eu\/it\/importazione-di-modelli-3d\/\" data-type=\"page\" data-id=\"432\">modelli 3D<\/a> e 400 <a href=\"https:\/\/test.sweethome3d.eu\/it\/importazione-di-texture\/\" data-type=\"page\" data-id=\"4928\">texture<\/a> gi\u00e0 incluse.<\/p>\n\n<p>Seleziona la voce di menu <em>Mobili &gt; Importa mobili&#8230;<\/em> per avviare la procedura guidata che ti aiuter\u00e0 a scegliere e dimensionare il file <a href=\"https:\/\/test.sweethome3d.eu\/it\/importazione-di-modelli-3d\/\" data-type=\"page\" data-id=\"432\">del modello 3D<\/a>, come mostrato nella figura 11. In Windows e macOS, puoi anche trascinare un file di modello 3D in una finestra di <a href=\"https:\/\/test.sweethome3d.eu\/it\/download\/\" data-type=\"page\" data-id=\"396\">Sweet Home 3D<\/a> per lanciare questa procedura guidata.<\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-53acd6ed wp-block-group-is-layout-constrained\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccde1ffcf&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccde1ffcf\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"825\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-22-1024x825.png\" alt=\"\" class=\"wp-image-4372 lazyload\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-22-1024x825.png 1024w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-22-300x242.png 300w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-22-112x90.png 112w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-22-768x619.png 768w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-22-1536x1237.png 1536w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-22.png 1562w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/825;\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">figura 11. Procedura guidata di importazione dell&#8217;arredamento <\/figcaption><\/figure>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<ol class=\"wp-block-list pl-14\">\n<li>Clicca su <em>Scegli il modello<\/em> e scegli il file <a href=\"https:\/\/test.sweethome3d.eu\/it\/importazione-di-modelli-3d\/\" data-type=\"page\" data-id=\"432\">del modello 3D<\/a> nella finestra di dialogo del file. Se hai trascinato in una finestra il file <a href=\"https:\/\/test.sweethome3d.eu\/it\/importazione-di-modelli-3d\/\" data-type=\"page\" data-id=\"432\">del modello 3D<\/a> che vuoi importare, questo viene selezionato automaticamente. Una volta caricato il modello, clicca su <em>Continua<\/em>.<\/li>\n\n\n\n<li>Orienta il modello con i pulsanti freccia in modo che la vista frontale visualizzi la faccia anteriore del <a href=\"https:\/\/test.sweethome3d.eu\/it\/importazione-di-modelli-3d\/\" data-type=\"page\" data-id=\"432\">modello 3D<\/a> e fai clic su <em>Continua<\/em>.<\/li>\n\n\n\n<li>Modifica se necessario il nome, le dimensioni, l&#8217;elevazione, il colore del modello importato e se questo modello \u00e8 mobile, \u00e8 una porta, una finestra o una scala. Quindi fai clic su <em>Continua<\/em>. <\/li>\n\n\n\n<li>Ruota il <a href=\"https:\/\/test.sweethome3d.eu\/it\/importazione-di-modelli-3d\/\" data-type=\"page\" data-id=\"432\">modello 3D<\/a> con il mouse per ottenere il punto di vista migliore sul modello per l&#8217;icona del modello visualizzata nel catalogo dei mobili, nell&#8217;elenco dei mobili e nella pianta della casa. Poi clicca su <em>Fine<\/em>.<\/li>\n<\/ol>\n\n<p>Una volta chiusa la procedura guidata di importazione dell&#8217;arredamento, il modello importato apparir\u00e0 nel catalogo degli arredi e\/o nella planimetria e nell&#8217;elenco degli arredi, a seconda delle opzioni scelte. Puoi utilizzarlo come qualsiasi <a href=\"https:\/\/test.sweethome3d.eu\/it\/importazione-di-modelli-3d\/\" data-type=\"page\" data-id=\"432\">modello 3D<\/a> del catalogo predefinito. <\/p>\n\n<div class=\"wp-block-group warning-banner is-layout-grid wp-container-core-group-is-layout-9649a0d9 wp-block-group-is-layout-grid\">\n<figure class=\"wp-block-image size-full is-resized wp-container-content-e1ca4baf\"><img decoding=\"async\" width=\"190\" height=\"190\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/11\/Frame-281.png\" alt=\"\" class=\"wp-image-786 lazyload\" style=\"--smush-placeholder-width: 190px; --smush-placeholder-aspect-ratio: 190\/190;width:130px\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/11\/Frame-281.png 190w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/11\/Frame-281-90x90.png 90w\" data-sizes=\"(max-width: 190px) 100vw, 190px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure>\n\n\n\n<p class=\"wp-container-content-1ed81c1b\">I modelli proposti nella <a href=\"https:\/\/test.sweethome3d.eu\/it\/modelli-3d-gratuiti\/\" data-type=\"page\" data-id=\"4869\">pagina dei modelli 3D gratuiti<\/a> possono anche essere <a href=\"https:\/\/test.sweethome3d.eu\/it\/importazione-di-modelli-3d\/#ModelsLibraries\" data-type=\"page\" data-id=\"432\">importati da gruppi di modelli<\/a> memorizzati in un file SH3F, disponibile nella sezione <em>SweetHome3D-models<\/em> all&#8217;indirizzo <a href=\"https:\/\/downloads.sourceforge.net\/sweethome3d\/\" target=\"_blank\" rel=\"noopener\">https:\/\/downloads.sourceforge.net\/sweethome3d\/<\/a> (funzione non disponibile nelle versioni Online e Mobile).<br\/>Per installare un file SH3F, basta fare doppio clic su di esso o selezionarlo dopo aver scelto la voce <em>Furniture &gt; Import furniture library<\/em> dal menu.<br\/>Per disinstallare un file SH3F, rimuovilo dalla cartella dei <a href=\"\/plugins\/\" data-type=\"page\" data-id=\"437\">plugin di<\/a> <a href=\"https:\/\/test.sweethome3d.eu\/it\/download\/\" data-type=\"page\" data-id=\"396\">Sweet Home 3D<\/a> e riavvia l&#8217;applicazione. Questa cartella viene visualizzata quando fai clic su qualsiasi file SH3F elencato nella sezione <em>Librerie di mobili<\/em> del riquadro <em>Librerie in uso<\/em>. Quest&#8217;ultimo riquadro viene visualizzato cliccando sul pulsante <em>Libraries&#8230;<\/em> che si trova in fondo alla finestra di dialogo Sweet Home 3D <em>About<\/em>.<br\/>Se necessario, puoi creare i tuoi file SH3F con il Furniture Library Editor, disponibile per il <a href=\"https:\/\/test.sweethome3d.eu\/it\/download\/\">download<\/a> su <a href=\"https:\/\/sourceforge.net\/projects\/sweethome3d\/files\/FurnitureLibraryEditor\/FurnitureLibraryEditor-2.2.jar\/download\" target=\"_blank\" rel=\"noopener\">sourceforge<\/a> (14,4 MB).<\/p>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\">Altre funzionalit\u00e0<\/h2>\n\n<h3 class=\"wp-block-heading\" id=\"drawing-dimensions\">Disegno di quote<\/h3>\n\n<div class=\"wp-block-group alignwide warning-banner border-t-0  warning-img-lg is-layout-grid wp-container-core-group-is-layout-9649a0d9 wp-block-group-is-layout-grid\">\n<figure class=\"wp-block-image size-full is-resized is-style-default\"><img decoding=\"async\" width=\"414\" height=\"240\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-11.png\" alt=\"\" class=\"wp-image-4377 lazyload\" style=\"--smush-placeholder-width: 414px; --smush-placeholder-aspect-ratio: 414\/240;object-fit:cover;width:130px\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-11.png 414w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-11-300x174.png 300w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-313-11-155x90.png 155w\" data-sizes=\"(max-width: 414px) 100vw, 414px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure>\n\n\n\n<p class=\"wp-container-content-1ed81c1b\">Per disegnare quote, fai prima clic sul pulsante Crea quote.<\/p>\n<\/div>\n\n<p>Puoi creare una nuova quota nella planimetria usando uno dei seguenti metodi:<\/p>\n\n<ul class=\"wp-block-list pl-14\">\n<li>Fai clic sul punto iniziale della nuova quota, fai clic sul suo punto finale, quindi fai clic una terza volta dopo aver spostato il puntatore del mouse per scegliere la dimensione delle linee di estensione disegnate a ogni estremit\u00e0 della linea di quota.<\/li>\n\n\n\n<li>Sposta il puntatore del mouse sul bordo di un elemento di arredo, sul lato del muro o sul lato della stanza che desideri misurare, fai doppio clic per accettare la quota temporanea disegnata nella planimetria, quindi fai clic una terza volta dopo aver scelto la dimensione delle sue linee di estensione.<\/li>\n<\/ul>\n\n<p>In entrambi i casi, la nuova quota non avr\u00e0 alcuna linea di estensione se non sposti il mouse tra il secondo e il terzo clic.<\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-53acd6ed wp-block-group-is-layout-constrained\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccde250ff&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccde250ff\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" width=\"964\" height=\"1024\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-23-964x1024.png\" alt=\"\" class=\"wp-image-4382 lazyload\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-23-964x1024.png 964w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-23-282x300.png 282w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-23-85x90.png 85w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-23-768x816.png 768w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-23-1445x1536.png 1445w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-23.png 1562w\" data-sizes=\"(max-width: 964px) 100vw, 964px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 964px; --smush-placeholder-aspect-ratio: 964\/1024;\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">figura 21. Disegno di quote <\/figcaption><\/figure>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group alignwide warning-banner border-t-0  warning-img-lg is-layout-grid wp-container-core-group-is-layout-9649a0d9 wp-block-group-is-layout-grid\">\n<figure class=\"wp-block-image size-full is-resized is-style-default\"><img decoding=\"async\" width=\"414\" height=\"240\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/dsa.png\" alt=\"\" class=\"wp-image-4387 lazyload\" style=\"--smush-placeholder-width: 414px; --smush-placeholder-aspect-ratio: 414\/240;object-fit:cover;width:130px\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/dsa.png 414w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/dsa-300x174.png 300w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/dsa-155x90.png 155w\" data-sizes=\"(max-width: 414px) 100vw, 414px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure>\n\n\n\n<p class=\"wp-container-content-1ed81c1b\">Per aggiungere testi liberi nella planimetria, fai prima clic sul pulsante Aggiungi testi.<\/p>\n<\/div>\n\n<h3 class=\"wp-block-heading\" id=\"adding-texts\">Aggiunta di testi<\/h3>\n\n<p>Fai clic nella posizione in cui desideri aggiungere un testo nella planimetria e immetti il testo nella finestra di dialogo che apparir\u00e0.<\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-53acd6ed wp-block-group-is-layout-constrained\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccde2974b&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccde2974b\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"391\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-24-1024x391.png\" alt=\"\" class=\"wp-image-4388 lazyload\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-24-1024x391.png 1024w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-24-300x114.png 300w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-24-236x90.png 236w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-24-768x293.png 768w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-24-1536x586.png 1536w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-24.png 1562w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/391;\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">figura 22. Un testo libero con stile in grassetto <\/figcaption><\/figure>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group alignwide warning-banner border-t-0  warning-img-lg is-layout-grid wp-container-core-group-is-layout-9649a0d9 wp-block-group-is-layout-grid\">\n<figure class=\"wp-block-image size-full is-resized is-style-default\"><img decoding=\"async\" width=\"414\" height=\"240\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/addingtime.png\" alt=\"\" class=\"wp-image-4389 lazyload\" style=\"--smush-placeholder-width: 414px; --smush-placeholder-aspect-ratio: 414\/240;object-fit:cover;width:130px\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/addingtime.png 414w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/addingtime-300x174.png 300w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/addingtime-155x90.png 155w\" data-sizes=\"(max-width: 414px) 100vw, 414px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure>\n\n\n\n<p class=\"wp-container-content-1ed81c1b\">In qualsiasi momento, puoi modificare le dimensioni e lo stile dei testi selezionati con i pulsanti di stile del testo.<\/p>\n<\/div>\n\n<div style=\"height:30px;width:0px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h3 class=\"wp-block-heading\" id=\"print\">Stampa<\/h3>\n\n<p>Una volta progettata la tua casa, puoi stamparla con i menu <em>File &gt; Stampa&#8230;<\/em> o <em>File &gt; Stampa su PDF&#8230;<\/em> e visualizzare l&#8217;anteprima del risultato con il menu <em>File &gt; Anteprima di stampa&#8230;<\/em>. Per impostazione predefinita, <a href=\"https:\/\/test.sweethome3d.eu\/it\/download\/\" data-type=\"page\" data-id=\"396\">Sweet Home 3D<\/a> stampa l&#8217;elenco degli arredi, la planimetria e l&#8217;attuale <a href=\"#editing-3d-view\">vista 3D<\/a> della casa, utilizzando dimensioni, margini e orientamento della carta predefiniti.<br\/>Scegli <em>File &gt; Imposta pagina&#8230;<\/em> dal menu per modificare questa scelta predefinita (funzionalit\u00e0 non disponibile nelle versioni <a href=\"\/online-manager\/\" data-type=\"page\" data-id=\"398\">Online<\/a> e Mobile), nonch\u00e9 la scala della planimetria stampata, l&#8217;intestazione e il pi\u00e8 di pagina, come mostrato nella figura 23. <\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-53acd6ed wp-block-group-is-layout-constrained\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccde2dbdf&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccde2dbdf\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"606\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-src=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-25-1024x606.png\" alt=\"\" class=\"wp-image-4390 lazyload\" data-srcset=\"https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-25-1024x606.png 1024w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-25-300x177.png 300w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-25-152x90.png 152w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-25-768x454.png 768w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-25-1536x909.png 1536w, https:\/\/test.sweethome3d.eu\/wp-content\/uploads\/2025\/12\/Frame-327-25.png 1562w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/606;\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">figura 23. Imposta pagina <\/figcaption><\/figure>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h3 class=\"wp-block-heading\" id=\"adding-plugins\">Aggiunta di plug-in<\/h3>\n\n<p>Le funzionalit\u00e0 di <a href=\"https:\/\/test.sweethome3d.eu\/it\/download\/\" data-type=\"page\" data-id=\"396\">Sweet Home 3D<\/a> possono essere estese grazie ai <a href=\"\/plugins\/\" data-type=\"page\" data-id=\"437\">plug-in<\/a>, che puoi anche <a href=\"\/plug-in-developers-guide\/\" data-type=\"page\" data-id=\"4964\">sviluppare<\/a> tu stesso se sei in grado di programmare in Java (funzione non disponibile nella versione <a href=\"\/online-manager\/\" data-type=\"page\" data-id=\"398\">Online<\/a> e Mobile).<br\/>Un plug-in \u00e8 un file SH3P memorizzato nella cartella <a href=\"\/plugins\/\" data-type=\"page\" data-id=\"437\">plug-in<\/a> di <a href=\"https:\/\/test.sweethome3d.eu\/it\/download\/\" data-type=\"page\" data-id=\"396\">Sweet Home 3D<\/a>. Per installare un file SH3P in questa cartella, basta fare doppio clic su questo file in Windows e macOS. In Linux, dovrai copiare il file SH3P nella sottocartella .eteks\/sweethome3d\/plugins della tua cartella utente se il doppio clic non funziona.<br\/>Una volta installato il <a href=\"\/plugins\/\" data-type=\"page\" data-id=\"437\">plug-in<\/a>, rilancia <a href=\"https:\/\/test.sweethome3d.eu\/it\/download\/\" data-type=\"page\" data-id=\"396\">Sweet Home 3D<\/a> per far apparire le nuove voci di menu e\/o i nuovi pulsanti corrispondenti alle caratteristiche del <a href=\"\/plugins\/\" data-type=\"page\" data-id=\"437\">plug-in<\/a>. Ad esempio, il plug-in <a href=\"https:\/\/sourceforge.net\/p\/sweethome3d\/plug-ins\/_discuss\/thread\/edd9ee60\/a726\/attachment\/RotateHomePlugin.zip\" target=\"_blank\" rel=\"noopener\">Home rotator<\/a> aggiunge due voci al menu <em>Plan<\/em> in grado di ruotare tutti gli elementi della pianta della casa in senso orario o antiorario.<\/p>\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-53acd6ed wp-block-group-is-layout-constrained\">\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Sweet Home 3D Tutorial - 1 Minute to create a mirror effect\" width=\"500\" height=\"281\" data-src=\"https:\/\/www.youtube.com\/embed\/_Lilr9r9JvU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe>\n<\/div><\/figure>\n<\/div>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prima di iniziare Introduzione Sweet Home 3D \u00e8 un&#8217;applicazione gratuita di interior design che ti aiuta a posizionare i tuoi mobili su una planimetria 2D di una casa, con un&#8217;anteprima 3D. Disponibile all&#8217;indirizzo https:\/\/test.sweethome3d.eu\/, questo programma \u00e8 rivolto a chi vuole progettare rapidamente i propri interni, sia che si tratti di un trasloco sia che<a href=\"https:\/\/test.sweethome3d.eu\/it\/guida-per-lutente-di-sweet-home-3d\/\">Continue reading <span class=\"sr-only\">&#8220;Guida all&#8217;uso di Sweet Home 3D&#8221;<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":15167,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-resources.php","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-10949","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/test.sweethome3d.eu\/it\/wp-json\/wp\/v2\/pages\/10949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.sweethome3d.eu\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/test.sweethome3d.eu\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/test.sweethome3d.eu\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/test.sweethome3d.eu\/it\/wp-json\/wp\/v2\/comments?post=10949"}],"version-history":[{"count":12,"href":"https:\/\/test.sweethome3d.eu\/it\/wp-json\/wp\/v2\/pages\/10949\/revisions"}],"predecessor-version":[{"id":18349,"href":"https:\/\/test.sweethome3d.eu\/it\/wp-json\/wp\/v2\/pages\/10949\/revisions\/18349"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/test.sweethome3d.eu\/it\/wp-json\/wp\/v2\/media\/15167"}],"wp:attachment":[{"href":"https:\/\/test.sweethome3d.eu\/it\/wp-json\/wp\/v2\/media?parent=10949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}